{"id":79762,"date":"2024-04-03T09:44:29","date_gmt":"2024-04-03T07:44:29","guid":{"rendered":"https:\/\/www.tressis.com\/?p=79762"},"modified":"2024-04-03T10:21:21","modified_gmt":"2024-04-03T08:21:21","slug":"primera-caida-ventas-de-tesla","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/","title":{"rendered":"Primera ca\u00edda en las ventas de Tesla"},"content":{"rendered":"<p>Ayer vivimos una sesi\u00f3n con p\u00e9rdidas en los principales \u00edndices de renta variable en Europa y Estados Unidos. En el Viejo Continente vimos retrocesos del 1,22% por parte del Eurostoxx, el DAX acab\u00f3 la jornada con un -1,09%, el CAC 40 con ca\u00eddas del 0,92% y el IBEX 35 corrigiendo un 0,89%.<\/p>\n<p>&nbsp;<\/p>\n<p>En Estados Unidos, las ventas se vivieron con m\u00e1s intensidad y cerraron todos los \u00edndices vestidos de rojo. El S&#038;P 500 con ca\u00eddas del 0,72%, el Nasdaq retrocedi\u00f3 un 0,95% y el Dow Jones con p\u00e9rdidas del 1%.<\/p>\n<p>&nbsp;<\/p>\n<p>Tesla tuvo su primera ca\u00edda en las ventas desde el inicio de la pandemia, entregando 386.810 veh\u00edculos en el primer trimestre de 2024, muy por debajo de la estimaci\u00f3n de los analistas de 449.080 veh\u00edculos. Las acciones retrocedieron un 5,5% y acumulan una ca\u00edda del 33% en lo que llevamos del a\u00f1o. La disminuci\u00f3n se atribuye al inicio de la producci\u00f3n del <a href=\"https:\/\/www.tesla.com\/es_es\/model3\" rel=\"noopener\" target=\"_blank\">Model 3<\/a> renovado, desv\u00edos de env\u00edos y un incendio en la f\u00e1brica de Berl\u00edn. A pesar de esto, Tesla sigue siendo el mayor vendedor de veh\u00edculos el\u00e9ctricos, superando a <a href=\"https:\/\/www.byd.com\/es-es\" rel=\"noopener\" target=\"_blank\">BYD<\/a> en el primer trimestre de 2024.<\/p>\n<p>&nbsp;<\/p>\n<p>En la jornada de ayer se conocieron muchos datos macroecon\u00f3micos que los \u00edndices de renta variable no acogieron para nada bien. La t\u00f3nica de los mercados de \u00abbuenas noticias son malas noticias\u00bb parece que est\u00e1 de vuelta. En Europa tuvimos los datos de PMI manufacturero referentes a marzo, que batieron las previsiones y sali\u00f3 una cifra de 46,1. Por parte de Alemania, se public\u00f3 la evoluci\u00f3n del IPC de marzo con un 2,2% en comparaci\u00f3n al 2,5% del mes anterior, gracias a la moderaci\u00f3n de precios de la alimentaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/04\/primera-caida-ventas-de-tesla-01.gif\" alt=\"Gr\u00e1fica de la inflaci\u00f3n alemana reduci\u00e9ndose\" \/><\/div>\n<p style=\"text-align: center; margin-top:20px;\">Continua la reducci\u00f3n de la inflaci\u00f3n alemana.<\/p>\n<p>&nbsp;<\/p>\n<p>Al otro lado del Atl\u00e1ntico, el n\u00famero de ofertas de empleo (JOLTS) para febrero sorprendi\u00f3 al alza, pero las revisiones a la baja de los datos de enero le quitaron mucho brillo al informe. Con la relaci\u00f3n entre vacantes y trabajadores desempleados disminuyendo a medida que aumenta el desempleo, se espera que las presiones salariales disminuyan a\u00fan m\u00e1s en el futuro.<\/p>\n<p>&nbsp;<\/p>\n<p>En la renta fija, se vieron aumentos de la rentabilidad exigida en los bonos soberanos a diez a\u00f1os. Es cierto que se dio una breve correcci\u00f3n cuando se public\u00f3 el informe de ofertas disponibles, pero esta no fue suficiente como para terminar el d\u00eda en positivo. Los tramos mas cortos como los bonos a dos a\u00f1os fueron los claros ganadores de la sesi\u00f3n, recortando su rentabilidad (subida de precio) un punto b\u00e1sico en Alemania y en Estados Unidos.<\/p>\n<p>&nbsp;<\/p>\n<p>En la agenda macroecon\u00f3mica, hoy tendremos el IPC y la tasa de desempleo en la zona euro. En Estados Unidos tenemos el cambio del empleo no agr\u00edcola ADP de marzo y las actualizaciones de los \u00edndices PMI e ISM. Aunque la cita m\u00e1s importante del d\u00eda la tenemos a las 18:10 con la comparecencia del presidente de la Reserva Federal, Jerome Powell.  <\/p>\n<p>&nbsp;<\/p>\n<p>Feliz mi\u00e9rcoles.<\/p>\n<p>&nbsp;<\/p>\n<p><center><strong>Javier Cantelar<\/strong><br \/>\nAnalista<\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer vivimos una sesi\u00f3n con p\u00e9rdidas en los principales \u00edndices de renta variable en Europa y Estados Unidos. En el Viejo Continente vimos retrocesos del 1,22% por parte del Eurostoxx, el DAX acab\u00f3 la jornada con un -1,09%, el CAC 40 con ca\u00eddas del 0,92% y el IBEX 35 corrigiendo un 0,89%. &nbsp; En Estados [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":79765,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[9523,9167,8650,9524,3726,9526,9525,4939,6552],"class_list":["post-79762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morning-meeting","tag-byd-co","tag-el-ibex-35-hoy","tag-empleo-ee-uu","tag-indices-ee-uu","tag-jerome-powell","tag-jolts-ee-uu","tag-model-3","tag-pmi-manufacturero","tag-tesla"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primera ca\u00edda en las ventas de Tesla<\/title>\n<meta name=\"description\" content=\"Ca\u00edda de ventas de Tesla atribuida a un incendio en la f\u00e1brica de Berl\u00edn, desv\u00edos de env\u00edos y el inicio de producci\u00f3n del Model 3 renovado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primera ca\u00edda en las ventas de Tesla\" \/>\n<meta property=\"og:description\" content=\"Ca\u00edda de ventas de Tesla atribuida a un incendio en la f\u00e1brica de Berl\u00edn, desv\u00edos de env\u00edos y el inicio de producci\u00f3n del Model 3 renovado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-03T07:44:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-03T08:21:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/04\/primera-caida-ventas-de-tesla.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Armando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Armando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/\"},\"author\":{\"name\":\"Armando\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\"},\"headline\":\"Primera ca\u00edda en las ventas de Tesla\",\"datePublished\":\"2024-04-03T07:44:29+00:00\",\"dateModified\":\"2024-04-03T08:21:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/\"},\"wordCount\":532,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/primera-caida-ventas-de-tesla.webp\",\"keywords\":[\"BYD Co.\",\"el Ibex 35 hoy\",\"empleo EE.UU.\",\"\u00edndices EE.UU.\",\"Jerome Powell\",\"JOLTS EE.UU.\",\"Model 3\",\"PMI manufacturero\",\"tesla\"],\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/\",\"name\":\"Primera ca\u00edda en las ventas de Tesla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/primera-caida-ventas-de-tesla.webp\",\"datePublished\":\"2024-04-03T07:44:29+00:00\",\"dateModified\":\"2024-04-03T08:21:21+00:00\",\"description\":\"Ca\u00edda de ventas de Tesla atribuida a un incendio en la f\u00e1brica de Berl\u00edn, desv\u00edos de env\u00edos y el inicio de producci\u00f3n del Model 3 renovado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/primera-caida-ventas-de-tesla.webp\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/primera-caida-ventas-de-tesla.webp\",\"width\":1100,\"height\":487,\"caption\":\"Interior de un Tesla Model 3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/primera-caida-ventas-de-tesla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morning meeting\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/morning-meeting-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Primera ca\u00edda en las ventas de Tesla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\",\"name\":\"Armando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"caption\":\"Armando\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primera ca\u00edda en las ventas de Tesla","description":"Ca\u00edda de ventas de Tesla atribuida a un incendio en la f\u00e1brica de Berl\u00edn, desv\u00edos de env\u00edos y el inicio de producci\u00f3n del Model 3 renovado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/","og_locale":"ca_ES","og_type":"article","og_title":"Primera ca\u00edda en las ventas de Tesla","og_description":"Ca\u00edda de ventas de Tesla atribuida a un incendio en la f\u00e1brica de Berl\u00edn, desv\u00edos de env\u00edos y el inicio de producci\u00f3n del Model 3 renovado.","og_url":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2024-04-03T07:44:29+00:00","article_modified_time":"2024-04-03T08:21:21+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/04\/primera-caida-ventas-de-tesla.webp","type":"image\/webp"}],"author":"Armando","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Armando","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/"},"author":{"name":"Armando","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae"},"headline":"Primera ca\u00edda en las ventas de Tesla","datePublished":"2024-04-03T07:44:29+00:00","dateModified":"2024-04-03T08:21:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/"},"wordCount":532,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/04\/primera-caida-ventas-de-tesla.webp","keywords":["BYD Co.","el Ibex 35 hoy","empleo EE.UU.","\u00edndices EE.UU.","Jerome Powell","JOLTS EE.UU.","Model 3","PMI manufacturero","tesla"],"articleSection":["Morning meeting"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/","url":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/","name":"Primera ca\u00edda en las ventas de Tesla","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/04\/primera-caida-ventas-de-tesla.webp","datePublished":"2024-04-03T07:44:29+00:00","dateModified":"2024-04-03T08:21:21+00:00","description":"Ca\u00edda de ventas de Tesla atribuida a un incendio en la f\u00e1brica de Berl\u00edn, desv\u00edos de env\u00edos y el inicio de producci\u00f3n del Model 3 renovado.","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/04\/primera-caida-ventas-de-tesla.webp","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/04\/primera-caida-ventas-de-tesla.webp","width":1100,"height":487,"caption":"Interior de un Tesla Model 3"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/primera-caida-ventas-de-tesla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Morning meeting","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/morning-meeting-ca\/"},{"@type":"ListItem","position":3,"name":"Primera ca\u00edda en las ventas de Tesla"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae","name":"Armando","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","caption":"Armando"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/79762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=79762"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/79762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/79765"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=79762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=79762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=79762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}