{"id":78337,"date":"2024-03-01T09:42:57","date_gmt":"2024-03-01T08:42:57","guid":{"rendered":"https:\/\/www.tressis.com\/?p=78337"},"modified":"2024-03-01T13:09:07","modified_gmt":"2024-03-01T12:09:07","slug":"reavivando-temores-a-la-inflacion","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/","title":{"rendered":"Reavivando los temores a la inflaci\u00f3n"},"content":{"rendered":"<p>La evoluci\u00f3n de los precios volvi\u00f3 a ser el centro de atenci\u00f3n de los inversores durante la sesi\u00f3n de ayer. En Europa, se publicaron las cifras preliminares de febrero del IPC de pa\u00edses como Espa\u00f1a, Francia y Alemania; estas se situaron en el 2,8%, 2,9% y 2,5%, respectivamente. Los datos son positivos y vinieron a confirmar que el proceso deflacionista contin\u00faa su curso, dado que las lecturas fueron inferiores a las del mes anterior.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Informe de febrero<\/strong><\/p>\n<div style=\"text-align: center; margin-bottom: 10px;\"><a href=\"https:\/\/www.tressis.com\/landing\/campana\/tressis-vision\/index.html?utm_campaign=descarga_paper&amp;utm_medium=blog_MMV&amp;utm_source=tressisvision\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone size-full wp-image-67199\" \nsrc=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg\" alt=\"Informe mensual - Tressis visi\u00f3n\" \nwidth=\"800\" height=\"354\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg 800w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-300x133.jpg 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-768x340.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>Al otro lado del Atl\u00e1ntico, en EE.UU., vio la luz el PCE (\u00edndice de precios de gasto en consumo personal) o, lo que es lo mismo, la variable en la que se fija la Reserva Federal para tomar decisiones en materia de pol\u00edtica monetaria. El dato general se situ\u00f3 en el 2,4% y la subyacente en el 2,8%. Al igual que en el Viejo Continente, la tendencia es positiva, aunque los precios contin\u00faan lejos del objetivo del 2%. La nota positiva en clave crecimiento, negativa en t\u00e9rminos de inflaci\u00f3n, fue que los ingresos personales crecieron un 1% respecto al mes anterior cuando se estimaba que aumentasen un 0,4%. Ello podr\u00eda avivar los temores de los efectos de segunda ronda.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center; margin-bottom:20px;\">Imagen: PCE de servicios sin energ\u00eda tiene un pico en el cambio mensual.<\/p>\n<div style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion-01.gif\" \/><\/div>\n<p style=\"text-align: center; margin-top:20px;\">Fuente: Bloomberg.<\/p>\n<p>&nbsp;<\/p>\n<p>En resumen, los \u00edndices de bolsa cerraron mixtos en Europa, con el DAX y FTSE 100 marcando un +0,44% y 0,07% respectivamente, mientras que el IBEX opac\u00f3 los resultados europeos con un -0,67% debido a la fuerte ca\u00edda de Grifols de casi 35%. Los parqu\u00e9s estadounidenses lograron brillar, en especial el Nasdaq con +0.90%, S&#038;P 500 0,52% y el Dow Jones Industrial +0,12%. Los protagonistas vuelven a ser los sectores de comunicaciones y tecnolog\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuando menos, fue curiosa la reacci\u00f3n de los bonos. Estos estaban registrando ligeras ca\u00eddas de los precios, con su consecuente alza de la rentabilidad ofrecida, hasta que las variables mencionadas anteriormente fueron publicadas. Este comportamiento podr\u00eda venir determinado por que los \u00faltimos datos de IPC fueron peores de lo estimado. Por ello, cuando ayer se confirm\u00f3 que las previsiones se hab\u00edan cumplido, los inversores se lanzaron a comprar deuda.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center; margin-bottom:20px;\">Imagen: Rentabilidad intradiaria del bono a 10 a\u00f1os de EE.UU.<\/p>\n<div style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion-02.gif\" \/><\/div>\n<p style=\"text-align: center; margin-top:20px;\">Fuente: Bloomberg.<\/p>\n<p>&nbsp;<\/p>\n<p>En la agenda macroecon\u00f3mica de hoy tendremos los PMI manufactureros en la zona euro (y a nivel pa\u00eds como Francia, Espa\u00f1a e Italia). Contaremos tambi\u00e9n con el mismo dato para Estados Unidos, adem\u00e1s del suministrado por ISM (Institute for Supply Management), y las previsiones de inflaci\u00f3n de la Universidad de Michigan.  <\/p>\n<p>&nbsp;<\/p>\n<p>Feliz viernes.<\/p>\n<p>&nbsp;<\/p>\n<p><center><strong>\u00c1lvaro Lleras Montoya<\/strong><br \/>\nAnalista<\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La evoluci\u00f3n de los precios volvi\u00f3 a ser el centro de atenci\u00f3n de los inversores durante la sesi\u00f3n de ayer. En Europa, se publicaron las cifras preliminares de febrero del IPC de pa\u00edses como Espa\u00f1a, Francia y Alemania; estas se situaron en el 2,8%, 2,9% y 2,5%, respectivamente. Los datos son positivos y vinieron a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":78342,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[1836,9167,8843,3688,9475],"class_list":["post-78337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morning-meeting","tag-deflacion","tag-el-ibex-35-hoy","tag-grifols","tag-ism","tag-precios-de-gasto-en-consumo-personal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reavivando los temores a la inflaci\u00f3n<\/title>\n<meta name=\"description\" content=\"La nota positiva en clave crecimiento, negativa en t\u00e9rminos de inflaci\u00f3n, fue que los ingresos personales aumentaron aunque no como se esperaba.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reavivando los temores a la inflaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La nota positiva en clave crecimiento, negativa en t\u00e9rminos de inflaci\u00f3n, fue que los ingresos personales aumentaron aunque no como se esperaba.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T08:42:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T12:09:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Armando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Armando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/\"},\"author\":{\"name\":\"Armando\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\"},\"headline\":\"Reavivando los temores a la inflaci\u00f3n\",\"datePublished\":\"2024-03-01T08:42:57+00:00\",\"dateModified\":\"2024-03-01T12:09:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/\"},\"wordCount\":452,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reavivando-temores-a-la-inflacion.webp\",\"keywords\":[\"deflaci\u00f3n\",\"el Ibex 35 hoy\",\"Grifols\",\"ISM\",\"Precios de Gasto en Consumo Personal\"],\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/\",\"name\":\"Reavivando los temores a la inflaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reavivando-temores-a-la-inflacion.webp\",\"datePublished\":\"2024-03-01T08:42:57+00:00\",\"dateModified\":\"2024-03-01T12:09:07+00:00\",\"description\":\"La nota positiva en clave crecimiento, negativa en t\u00e9rminos de inflaci\u00f3n, fue que los ingresos personales aumentaron aunque no como se esperaba.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reavivando-temores-a-la-inflacion.webp\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/reavivando-temores-a-la-inflacion.webp\",\"width\":1100,\"height\":487,\"caption\":\"reavivando temores a la inflaci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/reavivando-temores-a-la-inflacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morning meeting\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/morning-meeting-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reavivando los temores a la inflaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\",\"name\":\"Armando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"caption\":\"Armando\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reavivando los temores a la inflaci\u00f3n","description":"La nota positiva en clave crecimiento, negativa en t\u00e9rminos de inflaci\u00f3n, fue que los ingresos personales aumentaron aunque no como se esperaba.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/","og_locale":"ca_ES","og_type":"article","og_title":"Reavivando los temores a la inflaci\u00f3n","og_description":"La nota positiva en clave crecimiento, negativa en t\u00e9rminos de inflaci\u00f3n, fue que los ingresos personales aumentaron aunque no como se esperaba.","og_url":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2024-03-01T08:42:57+00:00","article_modified_time":"2024-03-01T12:09:07+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion.webp","type":"image\/webp"}],"author":"Armando","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Armando","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/"},"author":{"name":"Armando","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae"},"headline":"Reavivando los temores a la inflaci\u00f3n","datePublished":"2024-03-01T08:42:57+00:00","dateModified":"2024-03-01T12:09:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/"},"wordCount":452,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion.webp","keywords":["deflaci\u00f3n","el Ibex 35 hoy","Grifols","ISM","Precios de Gasto en Consumo Personal"],"articleSection":["Morning meeting"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/","url":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/","name":"Reavivando los temores a la inflaci\u00f3n","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion.webp","datePublished":"2024-03-01T08:42:57+00:00","dateModified":"2024-03-01T12:09:07+00:00","description":"La nota positiva en clave crecimiento, negativa en t\u00e9rminos de inflaci\u00f3n, fue que los ingresos personales aumentaron aunque no como se esperaba.","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion.webp","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2024\/03\/reavivando-temores-a-la-inflacion.webp","width":1100,"height":487,"caption":"reavivando temores a la inflaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/reavivando-temores-a-la-inflacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Morning meeting","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/morning-meeting-ca\/"},{"@type":"ListItem","position":3,"name":"Reavivando los temores a la inflaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae","name":"Armando","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","caption":"Armando"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/78337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=78337"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/78337\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/78342"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=78337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=78337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=78337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}