{"id":36821,"date":"2020-02-19T08:54:20","date_gmt":"2020-02-19T07:54:20","guid":{"rendered":"https:\/\/www.tressis.com\/blog\/?p=36821"},"modified":"2020-02-19T08:54:20","modified_gmt":"2020-02-19T07:54:20","slug":"incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/","title":{"rendered":"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL"},"content":{"rendered":"<p><center>Fuente: <a class=\"link4\" href=\"https:\/\/www.execyl.es\/protagonistas\/crecemos-tressis-nuevo-socio-protector-de-execyl\/\" target=\"_blank\" rel=\"noopener\">EXECyL<\/a><\/center><br \/>\nEstamos encantados de dar la bienvenida a EXECyL a TRESSIS, la entidad l\u00edder en gesti\u00f3n de patrimonios y planificaci\u00f3n financiera independiente a nivel nacional.<!--more--> Un grupo de profesionales que llevan caminando juntos desde el a\u00f1o 2000, obteniendo los mejores resultados en lo que m\u00e1s les apasiona: acompa\u00f1ar a las personas a lo largo de su vida financiera hasta alcanzar sus objetivos vitales.<\/p>\n<p>Personas con distintos perfiles que han formado parte de entidades financieras nacionales e internacionales de primer nivel que hoy son el motor de la compa\u00f1\u00eda.<\/p>\n<p>Sus valores, m\u00e1s que una se\u00f1a de identidad.<\/p>\n<p>Independencia. Solo lo que es bueno para sus clientes, es bueno para ellos.<\/p>\n<p>Confianza. Escuchar, comprender y acompa\u00f1ar siempre para que puedan tomar la decisi\u00f3n m\u00e1s acertada.<\/p>\n<p>Excelencia. Los mejores profesionales. Ese es el secreto para obtener los mejores resultados.<\/p>\n<p>Transparencia. Con la m\u00e1xima honestidad e informaci\u00f3n para que sean conscientes del proceso en todo momento.<\/p>\n<p>Todos los que forman parte de esta compa\u00f1\u00eda comparten estos valores, de los que se sienten orgullosos, y han hecho posible que Tressis sea la entidad s\u00f3lida y solvente que es hoy.<\/p>\n<p>Su mayor diferencia, su manera de hacer las cosas: Wealthinking. <\/p>\n<p>Una nueva perspectiva. O lo que es lo mismo, una nueva manera de entender la planificaci\u00f3n financiera de sus clientes. Eso es Wealthinking.<\/p>\n<p>La nueva forma de dise\u00f1ar, ejecutar y hacer el seguimiento de una estrategia de inversi\u00f3n continua, que ayude a sus clientes a tomar las mejores decisiones sobre su patrimonio, para que cuantifiquen y alcancen sus proyectos vitales.<\/p>\n<p>Un proceso en el que les acompa\u00f1an a lo largo de su vida, adapt\u00e1ndose para conseguir que sus metas vitales sean las que condicionen las decisiones financieras. Nunca al rev\u00e9s.<\/p>\n<p>Y eso, que desde el primer momento comprendan las necesidades de cada persona y busquen nuevas maneras de ver y gestionar su patrimonio para alcanzar sus objetivos, es Wealthinking.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuente: EXECyL Estamos encantados de dar la bienvenida a EXECyL a TRESSIS, la entidad l\u00edder en gesti\u00f3n de patrimonios y planificaci\u00f3n financiera independiente a nivel nacional.<\/p>\n","protected":false},"author":4,"featured_media":36822,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-36821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tressis-valladolid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL<\/title>\n<meta name=\"description\" content=\"\u00a1Crecemos! TRESSIS, nuevo socio protector de EXECyL\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL\" \/>\n<meta property=\"og:description\" content=\"\u00a1Crecemos! TRESSIS, nuevo socio protector de EXECyL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-19T07:54:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/EXECyL-tressis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL\",\"datePublished\":\"2020-02-19T07:54:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EXECyL-tressis.jpg\",\"articleSection\":[\"Tressis Valladolid\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/\",\"name\":\"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EXECyL-tressis.jpg\",\"datePublished\":\"2020-02-19T07:54:20+00:00\",\"description\":\"\u00a1Crecemos! TRESSIS, nuevo socio protector de EXECyL\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EXECyL-tressis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/EXECyL-tressis.jpg\",\"width\":1100,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tressis Valladolid\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/tressis-valladolid\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL","description":"\u00a1Crecemos! TRESSIS, nuevo socio protector de EXECyL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/","og_locale":"ca_ES","og_type":"article","og_title":"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL","og_description":"\u00a1Crecemos! TRESSIS, nuevo socio protector de EXECyL","og_url":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2020-02-19T07:54:20+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/EXECyL-tressis.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL","datePublished":"2020-02-19T07:54:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/EXECyL-tressis.jpg","articleSection":["Tressis Valladolid"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/","url":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/","name":"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/EXECyL-tressis.jpg","datePublished":"2020-02-19T07:54:20+00:00","description":"\u00a1Crecemos! TRESSIS, nuevo socio protector de EXECyL","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/EXECyL-tressis.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/EXECyL-tressis.jpg","width":1100,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/incorporacion-de-tressis-valladolid-a-la-fundacion-de-excelencia-empresarial-de-cyl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Tressis Valladolid","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/tressis-valladolid\/"},{"@type":"ListItem","position":3,"name":"Incorporaci\u00f3n de Tressis Valladolid a la Fundaci\u00f3n de Excelencia Empresarial de CyL"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/36821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=36821"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/36821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/36822"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=36821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=36821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=36821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}