{"id":36817,"date":"2020-03-05T18:24:00","date_gmt":"2020-03-05T17:24:00","guid":{"rendered":"https:\/\/www.tressis.com\/blog\/?p=36817"},"modified":"2020-03-05T18:24:00","modified_gmt":"2020-03-05T17:24:00","slug":"tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/","title":{"rendered":"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid"},"content":{"rendered":"<p><center>Fuente: <a class=\"link4\" href=\"https:\/\/www.castillayleoneconomica.es\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/?fbclid=IwAR05e_gMNvDqE1rbJkNhXgwkhh7lMjBZYgbkd-3ftkk3RSY-QO2FRAwHRtE\" target=\"_blank\" rel=\"noopener\">castillayleoneconomica<\/a><\/center><br \/>\nLa sociedad de valores Tressis, que a finales de 2019 gestionaba un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a, acaba de inaugurar su primera oficina en Castilla y Le\u00f3n, concretamente Valladolid.<!--more--> Con esta nueva delegaci\u00f3n, situada en la calle Mar\u00eda de Molina de la capital del Pisuerga, Tressis comienza su andadura en esta comunidad aut\u00f3noma ampliando su red de oficinas por la geograf\u00eda espa\u00f1ola.<\/p>\n<p>Guillermo Dom\u00ednguez Torres es socio director de Tressis en Castilla y Le\u00f3n y ser\u00e1 el encargado de dirigir la nueva oficina. Lleva vinculado a la entidad desde hace m\u00e1s de 6 a\u00f1os como director en sus oficinas de Madrid. Adem\u00e1s, es delegado territorial de la Asociaci\u00f3n Europea de Asesor\u00eda y Planificaci\u00f3n Financiera en Espa\u00f1a (EFPA), la asociaci\u00f3n profesional referente del sector, y previamente ha desarrollado su carrera como asesor financiero, fiscal y de empresas en Abante Asesores, Garrigues y Banco Santander.<\/p>\n<p>El equipo dirigido por Dom\u00ednguez Torres est\u00e1 formado por \u00c1lvaro Salazar, asesor que tambi\u00e9n proviene de Tressis Madrid, e Iciar Mart\u00edn en el \u00e1rea de atenci\u00f3n al cliente, y contempla la incorporaci\u00f3n de m\u00e1s asesores tanto en Valladolid como en el resto de la Castilla y Le\u00f3n.<\/p>\n<p>Apuesta<\/p>\n<p>Para Jos\u00e9 Miguel Mat\u00e9, consejero delegado de Tressis, la oficina de Valladolid \u201ces una apuesta importante para consolidar nuestro plan de crecimiento. Es una regi\u00f3n en la que los ahorradores e inversores valoran especialmente la confianza con su asesor y su entidad, as\u00ed como la calidad y personalizaci\u00f3n de servicio, aspectos clave en el modelo de gesti\u00f3n de patrimonios de Tressis, enfocado en ayudar a los clientes a alcanzar sus objetivos vitales. Esta comunidad aut\u00f3noma es estrat\u00e9gica para continuar creciendo con clientes que buscan un servicio diferencial y contamos con el mejor equipo para lograrlo\u201d.<\/p>\n<p>Dom\u00ednguez Torres, se\u00f1ala: \u201cestamos muy ilusionados con la apertura de esta nueva oficina. Los inversores castellanos y leoneses demandan cada vez m\u00e1s valor a\u00f1adido y especializaci\u00f3n en el asesoramiento, y un servicio que entiendan y se alinee con sus intereses, d\u00e1ndoles tranquilidad. Nuestra diferenciaci\u00f3n est\u00e1 en el enfoque, el tiempo e incluso el lenguaje que utilizamos con nuestros clientes, ayud\u00e1ndoles a definir objetivos, entender y dar sentido a sus inversiones, y trazar una estrategia m\u00e1s all\u00e1 de los productos. En definitiva, contribuyendo a planificar sus finanzas y optimizar la gesti\u00f3n de su patrimonio, no s\u00f3lo a nivel financiero sino tambi\u00e9n fiscal, con soluciones multiactivo a medida\u201d.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuente: castillayleoneconomica La sociedad de valores Tressis, que a finales de 2019 gestionaba un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a, acaba de inaugurar su primera oficina en Castilla y Le\u00f3n, concretamente Valladolid.<\/p>\n","protected":false},"author":4,"featured_media":36808,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-36817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tressis-valladolid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid<\/title>\n<meta name=\"description\" content=\"La sociedad de valores gestiona un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid\" \/>\n<meta property=\"og:description\" content=\"La sociedad de valores gestiona un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-05T17:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/guillermo-dominguez-torres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid\",\"datePublished\":\"2020-03-05T17:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/\"},\"wordCount\":455,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/guillermo-dominguez-torres.jpg\",\"articleSection\":[\"Tressis Valladolid\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/\",\"name\":\"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/guillermo-dominguez-torres.jpg\",\"datePublished\":\"2020-03-05T17:24:00+00:00\",\"description\":\"La sociedad de valores gestiona un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/guillermo-dominguez-torres.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/guillermo-dominguez-torres.jpg\",\"width\":1100,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tressis Valladolid\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/tressis-valladolid\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid","description":"La sociedad de valores gestiona un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/","og_locale":"ca_ES","og_type":"article","og_title":"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid","og_description":"La sociedad de valores gestiona un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a","og_url":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2020-03-05T17:24:00+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/guillermo-dominguez-torres.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid","datePublished":"2020-03-05T17:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/"},"wordCount":455,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/guillermo-dominguez-torres.jpg","articleSection":["Tressis Valladolid"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/","url":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/","name":"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/guillermo-dominguez-torres.jpg","datePublished":"2020-03-05T17:24:00+00:00","description":"La sociedad de valores gestiona un patrimonio de clientes de m\u00e1s de 4.400 millones de euros en Espa\u00f1a","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/guillermo-dominguez-torres.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/07\/guillermo-dominguez-torres.jpg","width":1100,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/tressis-desembarca-en-castilla-y-leon-con-la-apertura-de-una-oficina-en-valladolid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Tressis Valladolid","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/tressis-valladolid\/"},{"@type":"ListItem","position":3,"name":"Tressis desembarca en Castilla y Le\u00f3n con la apertura de una oficina en Valladolid"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/36817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=36817"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/36817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/36808"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=36817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=36817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=36817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}