{"id":36002,"date":"2021-04-08T12:35:42","date_gmt":"2021-04-08T12:35:42","guid":{"rendered":"https:\/\/www.tressis.com\/blog\/?p=36002"},"modified":"2023-05-29T17:43:22","modified_gmt":"2023-05-29T15:43:22","slug":"diez-cuestiones-importantes-ayudaran-declaracion-renta-2020","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/","title":{"rendered":"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020"},"content":{"rendered":"<p>Muchas han sido las sorpresas inesperadas que nos depar\u00f3 el a\u00f1o 2020.<!--more--><\/p>\n<p>El a\u00f1o pasado fue un a\u00f1o de cambios, de teletrabajo, de ERTE, del inicio de una nueva realidad. No obstante, hay cosas que no var\u00edan, entre ellas nuestras obligaciones frente a la Agencia Tributaria.<\/p>\n<p>Como cada a\u00f1o el pasado 7 de abril dio comienzo la campa\u00f1a para que los contribuyentes obligados a presentar su declaraci\u00f3n del impuesto sobre la renta de las personas f\u00edsicas correspondiente al ejercicio 2020 la confeccionen. A estos efectos, creemos importante que se tengan en cuenta los siguientes pronunciamientos a la hora de preparar la declaraci\u00f3n de la renta:<\/p>\n<p><center><strong><span style=\"color: #b01c2e;\">Rentas inmobiliarias<\/span><\/strong><\/center><br \/>\n<strong>Rentas imputadas:<\/strong> para la determinaci\u00f3n del rendimiento neto del capital inmobiliario, pueden deducirse todos los gastos necesarios para su obtenci\u00f3n, as\u00ed como las cantidades destinadas a la amortizaci\u00f3n del inmueble y de los dem\u00e1s bienes cedidos con el mismo, siempre que respondan a su depreciaci\u00f3n efectiva. Sin perjuicio de lo anterior, el Tribunal Supremo en su sentencia de 25 de febrero de 2021 ha resuelto que durante el tiempo en que el inmueble no est\u00e9 arrendado, aun existiendo una expectativa de alquiler, no cabe deducir gasto alguno y tributar\u00e1 en el IRPF como rentas imputadas con un m\u00ednimo equivalente al 2% o 1,1% del valor catastral.<\/p>\n<p><strong>Actividad de arrendamiento de inmuebles.<\/strong> <strong>Prohibici\u00f3n de pluriactividad de sus empleados.<\/strong> En relaci\u00f3n con el requisito exigido de que el arrendador tenga, al menos, una persona empleada con contrato laboral y a jornada completa, se debe precisar que solo se entender\u00e1 cumplido si dicho contrato es calificado como laboral por la normativa laboral vigente y es a jornada completa.<\/p>\n<p>Al respecto, debe precisarse que el empleado debe ser contratado por el arrendador persona f\u00edsica y dedicar la jornada completa a la ordenaci\u00f3n de la actividad de este. Ello implica que, si parte de dicha jornada la dedica el empleado al ejercicio de una actividad profesional propia o a la ordenaci\u00f3n de la actividad de otro contribuyente, se incumplir\u00edan los requisitos exigidos. Lo anterior supone el incumplimiento de los requisitos previstos en el art\u00edculo 27.2 de la LIRPF, por lo que la actividad de arrendamiento de inmuebles realizada no puede considerarse una actividad econ\u00f3mica a efectos de la exenci\u00f3n en el impuesto sobre el patrimonio (Consulta V3319-20).<\/p>\n<p><strong>Rentas atrasadas.<\/strong> <strong>Gasto deducible para la determinaci\u00f3n del rendimiento neto<\/strong>. El art\u00edculo 23.1 de la Ley 35\/2006 incluye entre los gastos que considera necesarios para la obtenci\u00f3n de los ingresos y, por tanto, deducibles para la determinaci\u00f3n del rendimiento neto \u201clos saldos de dudoso cobro en las condiciones que se establezcan reglamentariamente\u201d (Consulta V3301-20).<\/p>\n<p>Los gastos de conservaci\u00f3n y mantenimientos del inmueble no pueden considerarse como mayor importe del valor de adquisici\u00f3n. Los gastos efectuados de manera regular, con la finalidad de mantener el uso normal del bien y evitar su obsolescencia no pueden considerarse como mayor importe del valor de adquisici\u00f3n del mismo a la hora de su transmisi\u00f3n. Solo las inversiones y mejoras entendidas como aut\u00e9nticas inversiones que redundan en un aumento de la vida \u00fatil o habitabilidad del inmueble, o en aumento de la extensi\u00f3n o capacidad en otro tipo de bienes, deben considerarse, en el \u00e1mbito del IRPF, como mayor importe del valor de adquisici\u00f3n (RTEAC de 24 de septiembre de 2020).<\/p>\n<p><center><strong><span style=\"color: #b01c2e;\">Rentas del trabajo y actividades econ\u00f3micas<\/span><\/strong><\/center><br \/>\n<strong>Indemnizaci\u00f3n exenta:<\/strong> seg\u00fan lo establecido en el art\u00edculo 7 de la LIRPF estar\u00e1 exenta la indemnizaci\u00f3n por despido o cese del trabajador siempre que no supere los 180.000 euros. Pues bien, la Audiencia Nacional en su sentencia de 19 de febrero de 2020, consider\u00f3 que ante indicios de no estar ante una p\u00e9rdida forzosa del puesto de trabajo sino ante una rescisi\u00f3n pactada por ambas partes, tales como:<\/p>\n<ul>\n<li>edades de los empleados, pr\u00f3ximos a la jubilaci\u00f3n;<\/li>\n<li>la cuant\u00eda de las indemnizaciones, inferior a las procedentes;<\/li>\n<li>relaci\u00f3n entre lo percibido y lo que se habr\u00eda percibido de seguir en el puesto de trabajo hasta la edad de jubilaci\u00f3n;<\/li>\n<li>comunicaciones anteriores al acto de conciliaci\u00f3n donde ya se ordenaba el pago de la cantidad despu\u00e9s convenida por las partes;<\/li>\n<\/ul>\n<p>deber\u00e1 ser considerado como una consecuencia de \u00abconvenio, pacto o contrato\u00bb entre empresario y trabajador, supuesto para el que la norma no establece la exenci\u00f3n.<\/p>\n<p><strong>Rentas irregulares:<\/strong> los atrasos de pensiones de la Seguridad Social, correspondientes a varios a\u00f1os, reconocidos por sentencia judicial, tienen derecho a la reducci\u00f3n por irregulares prevista en el art\u00edculo 18.2 (RTEAC de 1 de junio de 2020).<\/p>\n<p><strong>Contrato de seguro en favor de su administrador:<\/strong> la prestaci\u00f3n se considerar\u00e1 como la retribuci\u00f3n realizada a un administrador en los t\u00e9rminos del art\u00edculo 17.2.e) Ley IRPF quedando, por tanto, sujeta al impuesto sobre la renta y no al impuesto sobre sucesiones y donaciones (Consulta Vinculante V3394-20).<\/p>\n<p><strong>Los gastos de suministro generados por el desarrollo de la actividad en la vivienda habitual con motivo de la COVID-19 no son deducibles:<\/strong> Para que determinados suministros de la vivienda habitual del contribuyente puedan tener la consideraci\u00f3n de gastos deducibles de una actividad econ\u00f3mica desarrollada por el contribuyente, es necesario que la vivienda habitual se encuentre parcialmente afecta a la actividad. Si la vivienda no se encuentra parcialmente afecta a la actividad, sino que su utilizaci\u00f3n ha sido motivada por una circunstancia ocasional y excepcional, los gastos por suministro no se podr\u00e1n deducir (CV3461-20)<\/p>\n<p><center><strong><span style=\"color: #b01c2e;\">Alteraciones patrimoniales<\/span><\/strong><\/center><br \/>\n<strong>Pr\u00e9stamo multidivisa:<\/strong> las p\u00e9rdidas patrimoniales derivadas del aumento de la deuda pendiente de un pr\u00e9stamo hipotecario formalizado en yenes, provocado por la fluctuaci\u00f3n del tipo de cambio yen\/euro, deber\u00edan integrarse en la base imponible general del IRPF, pero no en la renta del ahorro, pues no derivan de \u00abtransmisi\u00f3n\u00bb de ning\u00fan elemento patrimonial, sino de la mera fluctuaci\u00f3n del tipo de cambio.<\/p>\n<p><center><strong><span style=\"color: #b01c2e;\">Comisiones financieras<\/span><\/strong><\/center><br \/>\n<strong>Comisi\u00f3n de gesti\u00f3n discrecional de cartera:<\/strong> Por gastos inherentes a la adquisici\u00f3n o transmisi\u00f3n deben entenderse aquellos que tengan un nexo claro y preciso con las propias operaciones de adquisici\u00f3n o suscripci\u00f3n y de reembolso, circunstancia que no concurre en la comisi\u00f3n anual de gesti\u00f3n discrecional de cartera, que representa un gasto que se debe abonar peri\u00f3dicamente como contraprestaci\u00f3n de un servicio de gesti\u00f3n, que se calcula sobre el valor promedio que tenga la cartera gestionada, independientemente de las operaciones realizadas por la entidad gestora. En consecuencia, la comisi\u00f3n por la prestaci\u00f3n del servicio de gesti\u00f3n discrecional no podr\u00e1 tomarse en cuenta a los efectos de cuantificar la ganancia o p\u00e9rdida patrimonial derivada de dicho reembolso, ni de los posteriores reembolsos mediante los que se liquiden las inversiones (Consulta vinculante 3292- 20).<\/p>\n<p><strong>Comisi\u00f3n de asesoramiento en la venta de la empresa:<\/strong> los transmitentes que hayan soportado costes por honorarios derivados de las empresas de intermediaci\u00f3n en la venta de las participaciones podr\u00e1n minorar su valor de transmisi\u00f3n con el importe de dicha retribuci\u00f3n a la hora de cuantificar la ganancia patrimonial tributable en su IRPF (V2435-20).<\/p>\n<p>En Tressis estamos a su lado para resolver sus dudas, analizar su cartera de inversi\u00f3n y proponerle soluciones a medida. <a href=\"https:\/\/www.tressis.com\/landing\/reuniones\/index.html?utm_campaign=reuniones&amp;utm_medium=blog&amp;utm_source=renta_2020\" target=\"_blank\" rel=\"noopener\">Cons\u00faltenos sin compromiso<\/a>.<\/p>\n<p><center><strong>Lina Marcela Guerra<\/strong><br \/>\nDirectora Planificaci\u00f3n Patrimonial y Fiscal<\/center><\/p>\n<h6>El contenido de este documento no constituye asesoramiento, sino que es meramente divulgativo. En particular, cualquier decisi\u00f3n o actuaci\u00f3n relacionada con el contenido de esta alerta deber\u00eda ser objeto de an\u00e1lisis espec\u00edfico y adecuado a la situaci\u00f3n particular de que se trate.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Muchas han sido las sorpresas inesperadas que nos depar\u00f3 el a\u00f1o 2020.<\/p>\n","protected":false},"author":4,"featured_media":36004,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8561],"tags":[38,1814,2429,2982,3288,3679,5713],"class_list":["post-36002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscalidad","tag-38","tag-declaracion-de-la-renta","tag-erte","tag-gastos-deducibles","tag-impuestos","tag-irpf","tag-rentas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020<\/title>\n<meta name=\"description\" content=\"Como cada a\u00f1o, dio comienzo la campa\u00f1a para los contribuyentes obligados a presentar su declaraci\u00f3n del impuesto sobre la renta de las personas f\u00edsicas correspondiente al ejercicio 2020\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020\" \/>\n<meta property=\"og:description\" content=\"Como cada a\u00f1o, dio comienzo la campa\u00f1a para los contribuyentes obligados a presentar su declaraci\u00f3n del impuesto sobre la renta de las personas f\u00edsicas correspondiente al ejercicio 2020\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-08T12:35:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-29T15:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/04\/informacion-fiscal-2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020\",\"datePublished\":\"2021-04-08T12:35:42+00:00\",\"dateModified\":\"2023-05-29T15:43:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/\"},\"wordCount\":1305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/informacion-fiscal-2021.jpg\",\"keywords\":[\"2020\",\"declaraci\u00f3n de la renta\",\"erte\",\"gastos deducibles\",\"impuestos\",\"IRPF\",\"rentas\"],\"articleSection\":[\"Fiscalidad\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/\",\"name\":\"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/informacion-fiscal-2021.jpg\",\"datePublished\":\"2021-04-08T12:35:42+00:00\",\"dateModified\":\"2023-05-29T15:43:22+00:00\",\"description\":\"Como cada a\u00f1o, dio comienzo la campa\u00f1a para los contribuyentes obligados a presentar su declaraci\u00f3n del impuesto sobre la renta de las personas f\u00edsicas correspondiente al ejercicio 2020\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/informacion-fiscal-2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/informacion-fiscal-2021.jpg\",\"width\":1100,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscalitat\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/fiscalitat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020","description":"Como cada a\u00f1o, dio comienzo la campa\u00f1a para los contribuyentes obligados a presentar su declaraci\u00f3n del impuesto sobre la renta de las personas f\u00edsicas correspondiente al ejercicio 2020","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/","og_locale":"ca_ES","og_type":"article","og_title":"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020","og_description":"Como cada a\u00f1o, dio comienzo la campa\u00f1a para los contribuyentes obligados a presentar su declaraci\u00f3n del impuesto sobre la renta de las personas f\u00edsicas correspondiente al ejercicio 2020","og_url":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2021-04-08T12:35:42+00:00","article_modified_time":"2023-05-29T15:43:22+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/04\/informacion-fiscal-2021.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"6 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020","datePublished":"2021-04-08T12:35:42+00:00","dateModified":"2023-05-29T15:43:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/"},"wordCount":1305,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/04\/informacion-fiscal-2021.jpg","keywords":["2020","declaraci\u00f3n de la renta","erte","gastos deducibles","impuestos","IRPF","rentas"],"articleSection":["Fiscalidad"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/","url":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/","name":"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/04\/informacion-fiscal-2021.jpg","datePublished":"2021-04-08T12:35:42+00:00","dateModified":"2023-05-29T15:43:22+00:00","description":"Como cada a\u00f1o, dio comienzo la campa\u00f1a para los contribuyentes obligados a presentar su declaraci\u00f3n del impuesto sobre la renta de las personas f\u00edsicas correspondiente al ejercicio 2020","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/04\/informacion-fiscal-2021.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2021\/04\/informacion-fiscal-2021.jpg","width":1100,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/diez-cuestiones-importantes-ayudaran-declaracion-renta-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Fiscalitat","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/fiscalitat\/"},{"@type":"ListItem","position":3,"name":"Diez cuestiones importantes que te ayudar\u00e1n en tu declaraci\u00f3n de la renta 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/36002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=36002"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/36002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/36004"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=36002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=36002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=36002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}