{"id":344,"date":"2012-05-25T10:25:49","date_gmt":"2012-05-25T08:25:49","guid":{"rendered":"http:\/\/blog.tressis.com\/?p=344"},"modified":"2012-05-25T10:25:49","modified_gmt":"2012-05-25T08:25:49","slug":"la-incertidumbre-politica-pasa-factura-2","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/","title":{"rendered":"La incertidumbre pol\u00edtica pasa factura"},"content":{"rendered":"<p>Buenos d\u00edas.<\/p>\n<p>El verde se extendi\u00f3 por los parqu\u00e9s europeos ante los rumores de que el BCE podr\u00eda estar preparando una inyecci\u00f3n coordinada de liquidez. Rumores que pesaron m\u00e1s que el mal sabor de boca que dej\u00f3 un PMI manufacturero de China menor de lo esperado o la ca\u00edda del \u00edndice de confianza empresarial alem\u00e1n IFO, que indican una desaceleraci\u00f3n econ\u00f3mica.<!--more--><\/p>\n<p>En la misma l\u00ednea la lectura preliminar de los PMI manufactureros de la zona euro muestra un mayor deterioro de dicha actividad para los pr\u00f3ximos meses. Parece, se\u00f1oras y se\u00f1ores, que el \u201cjuego\u201d pol\u00edtico entre los dirigentes europeos afecta a la econom\u00eda real de TODOS los pa\u00edses que conforman la zona euro. La incertidumbre pol\u00edtica pasa factura.<\/p>\n<p>Ante este panorama econ\u00f3mico es m\u00e1s factible que el BCE act\u00fae, lo que sin duda mantiene el \u00e1nimo en los mercados financieros en las \u00faltimas sesiones. Aunque ser\u00e1 dif\u00edcil que las reacciones alcistas en las acciones europeas se mantengan sin un est\u00edmulo por parte de la autoridad monetaria, puesto que el conjunto euro carece de \u201cautosuficiencia econ\u00f3mica\u201d para crecer. \u00bfVeremos pronto intervenci\u00f3n del BCE? No es probable en el futuro m\u00e1s inmediato salvo que la situaci\u00f3n se deteriore \u201cm\u00e1s a\u00fan\u201d con o sin Grecia. Mientras, cruce dial\u00e9ctico entre las autoridades:\u00a0 primeros ministros, similares y suced\u00e1neos que reclaman a Draghi animarse con la compra de deuda p\u00fablica; y Draghi devolviendo la pelota pidiendo mayores avances hacia una integraci\u00f3n fiscal y pol\u00edtica. M\u00e1s de lo mismo.<\/p>\n<p>Pero dentro del mercado de renta fija destaca la ca\u00edda de las primas de riesgo de las curvas perif\u00e9ricas, as\u00ed como el despertar de un mayor apetito por la <em>cuisine fran\u00e7aise<\/em> por parte de aquellos inversores que buscan rentabilidad (teniendo en cuenta que los bonos alemanes siguen en rentabilidades minim\u00edsimas) dentro de pa\u00edses <em>core<\/em> o <em>semi-core<\/em> (como podr\u00eda ser el caso).<\/p>\n<p>En el resto del mundo la vida sigue con un ojo puesto en Europa y otro en los temores a una desaceleraci\u00f3n global (temas recurrentes), con EEUU y China que van haciendo lo que pueden para salvar sus muebles, y si no tambi\u00e9n les queda la esperanza de que sus banqueros centrales act\u00faen, con la ventaja de que en los respectivos gallineros de Washington y Pek\u00edn no se hablan <em>17 idiomas<\/em>.<\/p>\n<p>Buen d\u00eda,<\/p>\n<p><strong>Montserrat Formoso Fraga<\/strong><br \/>\nGesti\u00f3n de Carteras<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas. El verde se extendi\u00f3 por los parqu\u00e9s europeos ante los rumores de que el BCE podr\u00eda estar preparando una inyecci\u00f3n coordinada de liquidez. Rumores que pesaron m\u00e1s que el mal sabor de boca que dej\u00f3 un PMI manufacturero de China menor de lo esperado o la ca\u00edda del \u00edndice de confianza empresarial alem\u00e1n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[],"class_list":["post-344","post","type-post","status-publish","format-standard","hentry","category-morning-meeting"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La incertidumbre pol\u00edtica pasa factura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La incertidumbre pol\u00edtica pasa factura\" \/>\n<meta property=\"og:description\" content=\"Buenos d\u00edas. El verde se extendi\u00f3 por los parqu\u00e9s europeos ante los rumores de que el BCE podr\u00eda estar preparando una inyecci\u00f3n coordinada de liquidez. Rumores que pesaron m\u00e1s que el mal sabor de boca que dej\u00f3 un PMI manufacturero de China menor de lo esperado o la ca\u00edda del \u00edndice de confianza empresarial alem\u00e1n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-25T08:25:49+00:00\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"La incertidumbre pol\u00edtica pasa factura\",\"datePublished\":\"2012-05-25T08:25:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/\"},\"wordCount\":433,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/\",\"name\":\"La incertidumbre pol\u00edtica pasa factura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"datePublished\":\"2012-05-25T08:25:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/la-incertidumbre-politica-pasa-factura-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morning meeting\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/morning-meeting-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La incertidumbre pol\u00edtica pasa factura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La incertidumbre pol\u00edtica pasa factura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/","og_locale":"ca_ES","og_type":"article","og_title":"La incertidumbre pol\u00edtica pasa factura","og_description":"Buenos d\u00edas. El verde se extendi\u00f3 por los parqu\u00e9s europeos ante los rumores de que el BCE podr\u00eda estar preparando una inyecci\u00f3n coordinada de liquidez. Rumores que pesaron m\u00e1s que el mal sabor de boca que dej\u00f3 un PMI manufacturero de China menor de lo esperado o la ca\u00edda del \u00edndice de confianza empresarial alem\u00e1n [&hellip;]","og_url":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2012-05-25T08:25:49+00:00","author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"La incertidumbre pol\u00edtica pasa factura","datePublished":"2012-05-25T08:25:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/"},"wordCount":433,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"articleSection":["Morning meeting"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/","url":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/","name":"La incertidumbre pol\u00edtica pasa factura","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"datePublished":"2012-05-25T08:25:49+00:00","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/la-incertidumbre-politica-pasa-factura-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Morning meeting","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/morning-meeting-ca\/"},{"@type":"ListItem","position":3,"name":"La incertidumbre pol\u00edtica pasa factura"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=344"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/344\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}