{"id":31990,"date":"2019-10-22T10:43:34","date_gmt":"2019-10-22T10:43:34","guid":{"rendered":"http:\/\/www.tressis.com\/blog\/?p=31990"},"modified":"2022-01-07T17:01:56","modified_gmt":"2022-01-07T17:01:56","slug":"intereses-moratorios-o-indemnizatorios","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/","title":{"rendered":"Intereses moratorios o indemnizatorios"},"content":{"rendered":"<p>Debemos iniciar este art\u00edculo recordando que existen a nivel civil tres clases de intereses recogidos y regulados en el ordenamiento jur\u00eddico espa\u00f1ol:<!--more--><\/p>\n<ul>\n<li>Compensatorios, que son los que se adecuan a la productividad natural del dinero.<\/li>\n<\/ul>\n<ul>\n<li>Moratorios, los que responden a la necesidad de reparar o indemnizar el da\u00f1o causado por el retraso en el cumplimiento. Tienen su reflejo civil en el 1.108 C\u00f3digo Civil.<\/li>\n<\/ul>\n<ul>\n<li>Sancionadores, que cumplen una funci\u00f3n de penalizaci\u00f3n para el supuesto de retraso en el pago.<\/li>\n<\/ul>\n<p>Pues bien, a nivel fiscal el impuesto sobre la renta de las personas f\u00edsicas (IRPF) califica los tipos de inter\u00e9s antes vistos en funci\u00f3n de su naturaleza remuneratoria o indemnizatoria.<\/p>\n<p>As\u00ed, los intereses remuneratorios o compensatorios, dado que constituyen la contraprestaci\u00f3n, bien de la entrega de un capital que debe ser reintegrado en el futuro, bien del aplazamiento en el pago, otorgado por el acreedor o pactado por las partes, tributar\u00e1n en el IRPF como rendimientos del capital mobiliario.<\/p>\n<p>Por su parte, los intereses moratorios o sancionadores, dado que tienen como finalidad resarcir al acreedor por los da\u00f1os y perjuicios derivados del incumplimiento de una obligaci\u00f3n o el retraso en su correcto cumplimiento (intereses de demora, indemnizaciones por la resoluci\u00f3n de contratos V2648-15), no pueden calificarse como rendimientos del capital mobiliario sino como ganancias patrimoniales no derivadas de una transmisi\u00f3n, por lo que deber\u00e1n ser integrados en la base imponible general del contribuyente.<\/p>\n<p>Sin perjuicio del se\u00f1alado criterio de la Administraci\u00f3n tributaria, es importante precisar que el Tribunal Superior de Justicia de la Comunidad Valenciana* en una reciente sentencia ha considerado que los intereses de demora que la Administraci\u00f3n tributaria viene obligada a abonar, por ejemplo en el caso de la devoluci\u00f3n de ingresos indebidos, no deben considerarse como una ganancia patrimonial del contribuyente. Tal interpretaci\u00f3n se fundamenta en los siguientes criterios:<\/p>\n<p>En primer lugar, porque la naturaleza indemnizatoria de los intereses de demora se ver\u00eda comprometida si el contribuyente no acaba recibiendo la totalidad de dichos intereses porque tiene que tributar por ellos en el IRPF.<\/p>\n<p>En segundo lugar, porque no resulta admisible que el contribuyente genere un beneficio de una actuaci\u00f3n contraria a Derecho.<\/p>\n<p>Asimismo, respetando esta l\u00ednea argumental entiende el Tribunal que los intereses de demora suspensivos, pagados, en su caso, por el contribuyente en un procedimiento ante la Administraci\u00f3n tributaria no deben ser conceptualizados como indemnizatorios y por tanto ser calificados como p\u00e9rdida patrimonial por parte del contribuyente.<\/p>\n<p>Respecto a los supuestos de condenas en costas en procedimientos judiciales, la Direcci\u00f3n General de Tributos viene manteniendo en diversos pronunciamientos (consultas n\u00ba 0154-05, 0172-05, V0588-05, V1265-06, V0343-09, V0268-10, V0974-13, V2909-14 y V4846-16) que la parte condenada al pago no est\u00e1 satisfaciendo rendimientos profesionales a los abogados y procuradores de la parte vencedora, sino que le est\u00e1 pagando una indemnizaci\u00f3n.<\/p>\n<p>Teniendo en cuenta dicha calificaci\u00f3n, la parte vendedora deber\u00e1 integrar en su IRPF una ganancia patrimonial no sujeta a retenci\u00f3n, sin importar si las costas son abonadas al propio contribuyente o a una compa\u00f1\u00eda de seguros como consecuencia de un seguro de responsabilidad civil.  <\/p>\n<h6>*Tribunal Superior de Justicia de la Comunidad Valenciana, Sala de lo Contencioso-administrativo, Secci\u00f3n 3\u00aa, S de 8 de octubre de 2018 Ponente: Baeza D\u00edaz-Portales, Manuel Jos\u00e9 &#8211; N\u00ba de Sentencia: 917\/2018 &#8211; N\u00ba de Recurso: 223\/2015.<\/h6>\n<p><center><strong>Lina Marcela Guerra<\/strong><\/center><center>Directora de Planificaci\u00f3n Patrimonial y Fiscal<\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debemos iniciar este art\u00edculo recordando que existen a nivel civil tres clases de intereses recogidos y regulados en el ordenamiento jur\u00eddico espa\u00f1ol:<\/p>\n","protected":false},"author":4,"featured_media":32461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8561],"tags":[],"class_list":["post-31990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscalidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intereses moratorios o indemnizatorios<\/title>\n<meta name=\"description\" content=\"No deber\u00e1n clasificarse en todos los casos como ganancias patrimoniales sujetas a tributaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intereses moratorios o indemnizatorios\" \/>\n<meta property=\"og:description\" content=\"No deber\u00e1n clasificarse en todos los casos como ganancias patrimoniales sujetas a tributaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-22T10:43:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-07T17:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2019\/07\/fiscalidad-intereses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"Intereses moratorios o indemnizatorios\",\"datePublished\":\"2019-10-22T10:43:34+00:00\",\"dateModified\":\"2022-01-07T17:01:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/\"},\"wordCount\":591,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/fiscalidad-intereses.jpg\",\"articleSection\":[\"Fiscalidad\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/\",\"name\":\"Intereses moratorios o indemnizatorios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/fiscalidad-intereses.jpg\",\"datePublished\":\"2019-10-22T10:43:34+00:00\",\"dateModified\":\"2022-01-07T17:01:56+00:00\",\"description\":\"No deber\u00e1n clasificarse en todos los casos como ganancias patrimoniales sujetas a tributaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/fiscalidad-intereses.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/fiscalidad-intereses.jpg\",\"width\":1100,\"height\":487,\"caption\":\"Intereses moratorios o indemnizatorios\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/intereses-moratorios-o-indemnizatorios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"agregado\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/blog\\\/etiquetas\\\/agregado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Intereses moratorios o indemnizatorios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intereses moratorios o indemnizatorios","description":"No deber\u00e1n clasificarse en todos los casos como ganancias patrimoniales sujetas a tributaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/","og_locale":"ca_ES","og_type":"article","og_title":"Intereses moratorios o indemnizatorios","og_description":"No deber\u00e1n clasificarse en todos los casos como ganancias patrimoniales sujetas a tributaci\u00f3n","og_url":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2019-10-22T10:43:34+00:00","article_modified_time":"2022-01-07T17:01:56+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2019\/07\/fiscalidad-intereses.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"Intereses moratorios o indemnizatorios","datePublished":"2019-10-22T10:43:34+00:00","dateModified":"2022-01-07T17:01:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/"},"wordCount":591,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2019\/07\/fiscalidad-intereses.jpg","articleSection":["Fiscalidad"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/","url":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/","name":"Intereses moratorios o indemnizatorios","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2019\/07\/fiscalidad-intereses.jpg","datePublished":"2019-10-22T10:43:34+00:00","dateModified":"2022-01-07T17:01:56+00:00","description":"No deber\u00e1n clasificarse en todos los casos como ganancias patrimoniales sujetas a tributaci\u00f3n","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2019\/07\/fiscalidad-intereses.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2019\/07\/fiscalidad-intereses.jpg","width":1100,"height":487,"caption":"Intereses moratorios o indemnizatorios"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/intereses-moratorios-o-indemnizatorios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"agregado","item":"https:\/\/www.tressis.com\/blog\/etiquetas\/agregado\/"},{"@type":"ListItem","position":3,"name":"Intereses moratorios o indemnizatorios"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/31990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=31990"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/31990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/32461"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=31990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=31990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=31990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}