{"id":27015,"date":"2017-10-09T10:47:37","date_gmt":"2017-10-09T08:47:37","guid":{"rendered":"http:\/\/www.tressis.com\/blog\/?p=27015"},"modified":"2017-10-09T10:47:37","modified_gmt":"2017-10-09T08:47:37","slug":"impacto-economico-del-brexit","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/","title":{"rendered":"El impacto econ\u00f3mico del brexit"},"content":{"rendered":"<p>Wall Street volvi\u00f3 a marcar un nuevo triple m\u00e1ximo el viernes y no hay excusas con las que atacar.<!--more--><\/p>\n<p>Simplemente el entorno es favorable al riesgo, adem\u00e1s de que lo mejor que se puede extraer es que en las \u00faltimas semanas no solo han sido las tecnol\u00f3gicas las que han marcado el ritmo. Queda entonces por ver si la temporada de resultados que comienza esta semana sostiene todo esto.<\/p>\n<p>Lo que no se sostiene, se mire por donde se mire, es la famosa DUI. La fuga de empresas de Catalu\u00f1a puede llegar a ser lo suficientemente demoledora para la econom\u00eda de la regi\u00f3n como para haber calmado los \u00e1nimos. Cosas que suceden cuando se retuerce la ley a voluntad, pero es que quien no hubiera previsto unas consecuencias tan negativas merece un aplauso mientras contempla el abandono de las grandes corporaciones catalanas.<\/p>\n<p>Tampoco hubo un exceso de celo al calcular el impacto econ\u00f3mico del <i>brexit<\/i>, pero en las islas ya es demasiado tarde para los lamentos. Adem\u00e1s de las continuas muestras de desconocimiento de la situaci\u00f3n para hoy y ma\u00f1ana, la rebeli\u00f3n entre los <i>tories<\/i> contra May puede ser otra puntada que desaliente a los brit\u00e1nicos de la separaci\u00f3n que dicen es inevitable.<\/p>\n<p>Pasando al terreno fundamental, el informe de empleo de EEUU vale por partes. Los huracanes han distorsionado por completo el mercado laboral estadounidense en septiembre, que recoge destrucci\u00f3n de puestos de trabajo por primera vez en siete a\u00f1os. Sin embargo, adem\u00e1s de la bajada de la tasa de paro al 4,2%, destaca el crecimiento de los salarios al 2,9%, un dato con algo m\u00e1s de calado por la necesidad que tiene la Reserva Federal de que as\u00ed sea. Tambi\u00e9n conviene hacer una parada en el mundo del petr\u00f3leo del pa\u00eds, pues la subida de los precios ha vuelto a meter en el mercado a los <i>frackers<\/i>, provocando no solo la ca\u00edda del precio del barril, sino tambi\u00e9n la idea de que la sobreoferta sigue igual de presente.<\/p>\n<p>Tan solo queda comentar la debilidad publicada en el PMI de servicios chino elaborado por Caixin. Por dos razones es importante. La primera es el dato en s\u00ed, que situ\u00e1ndose tan cerca de la barrera de los 50 puntos como se sit\u00faa, ha encendido alguna que otra alarma. Y la segunda es que contradice los datos del Gobierno, que mostraban un sector terciario bastante m\u00e1s potente que el que refleja un indicador independiente.<\/p>\n<p>Buen d\u00eda.<\/p>\n<p><strong>Am\u00edlcar Barrios Vilallonga<\/strong><br \/>\nDirecci\u00f3n de Inversiones<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wall Street volvi\u00f3 a marcar un nuevo triple m\u00e1ximo el viernes y no hay excusas con las que atacar.<\/p>\n","protected":false},"author":4,"featured_media":27016,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[811,816,1080,2136,2873,3213,3489,4021,5761,6665,6955],"class_list":["post-27015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morning-meeting","tag-brexit","tag-britanicos","tag-cataluna","tag-dui","tag-frackers","tag-huracanes","tag-informe-empleo-eeuu","tag-may","tag-reserva-federal","tag-tories","tag-wall-street"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El impacto econ\u00f3mico del brexit<\/title>\n<meta name=\"description\" content=\"En las islas ya es demasiado tarde para los lamentos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El impacto econ\u00f3mico del brexit\" \/>\n<meta property=\"og:description\" content=\"En las islas ya es demasiado tarde para los lamentos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-09T08:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/10\/20171009-mmv.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"El impacto econ\u00f3mico del brexit\",\"datePublished\":\"2017-10-09T08:47:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/\"},\"wordCount\":442,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/20171009-mmv.jpg\",\"keywords\":[\"Brexit\",\"brit\u00e1nicos\",\"Catalu\u00f1a\",\"DUI\",\"frackers\",\"huracanes\",\"informe empleo EEUU\",\"May\",\"Reserva Federal\",\"tories\",\"Wall Street\"],\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/\",\"name\":\"El impacto econ\u00f3mico del brexit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/20171009-mmv.jpg\",\"datePublished\":\"2017-10-09T08:47:37+00:00\",\"description\":\"En las islas ya es demasiado tarde para los lamentos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/20171009-mmv.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/20171009-mmv.jpg\",\"width\":1100,\"height\":487,\"caption\":\"El impacto econ\u00f3mico del brexit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/impacto-economico-del-brexit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El impacto econ\u00f3mico del brexit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El impacto econ\u00f3mico del brexit","description":"En las islas ya es demasiado tarde para los lamentos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/","og_locale":"ca_ES","og_type":"article","og_title":"El impacto econ\u00f3mico del brexit","og_description":"En las islas ya es demasiado tarde para los lamentos","og_url":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2017-10-09T08:47:37+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/10\/20171009-mmv.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"El impacto econ\u00f3mico del brexit","datePublished":"2017-10-09T08:47:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/"},"wordCount":442,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/10\/20171009-mmv.jpg","keywords":["Brexit","brit\u00e1nicos","Catalu\u00f1a","DUI","frackers","huracanes","informe empleo EEUU","May","Reserva Federal","tories","Wall Street"],"articleSection":["Morning meeting"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/","url":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/","name":"El impacto econ\u00f3mico del brexit","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/10\/20171009-mmv.jpg","datePublished":"2017-10-09T08:47:37+00:00","description":"En las islas ya es demasiado tarde para los lamentos","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/10\/20171009-mmv.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/10\/20171009-mmv.jpg","width":1100,"height":487,"caption":"El impacto econ\u00f3mico del brexit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/impacto-economico-del-brexit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"El impacto econ\u00f3mico del brexit"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/27015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=27015"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/27015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/27016"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=27015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=27015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=27015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}