{"id":25810,"date":"2017-06-15T18:40:57","date_gmt":"2017-06-15T16:40:57","guid":{"rendered":"http:\/\/www.tressis.com\/blog\/?p=25810"},"modified":"2023-05-26T13:31:07","modified_gmt":"2023-05-26T11:31:07","slug":"adriza-neutral-comentario-semanal-15062017","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/","title":{"rendered":"Adriza Neutral. Comentario semanal (15\/06\/2017)"},"content":{"rendered":"<p>El acontecimiento m\u00e1s relevante de la \u00faltima semana ha sido la subida de tipos por parte de la Reserva Federal y sus previsiones para reducir su balance, pero lo que nos ha sorprendido ha sido la lectura de los mercados porque parece que los agentes no conf\u00edan en la previsiones del Banco Central.<!--more--><\/p>\n<p> Como siempre comenzaremos por los resultados,  se mantiene un modesto 0,12% de revalorizaci\u00f3n en el mes: <\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/06\/adriza-neutral.png\" alt=\"\" width=\"387\" height=\"164\" class=\"aligncenter size-full wp-image-25811\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/06\/adriza-neutral.png 387w, https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/06\/adriza-neutral-300x127.png 300w\" sizes=\"(max-width: 387px) 100vw, 387px\" \/><\/p>\n<p>Despu\u00e9s de los recientes datos de la econom\u00eda norteamericana que conforman un escenario macro con un bajo crecimiento econ\u00f3mico y con una tasa de inflaci\u00f3n que modera su crecimiento alejandose del 2%, la Reserva Federal ha subido los tipos hasta un rango entre el 1% y el 1,25%. Adem\u00e1s, hecho que en nuestra opini\u00f3n es m\u00e1s importante, ha confirmado, e incluso desvelado parcialmente, su programa para reducir el tama\u00f1o de su balance.<\/p>\n<p>Los recientes datos de inflaci\u00f3n en EEUU no han confirmado la convergencia entre inflaci\u00f3n general y subyacente pronosticados a principios del ejercicio, esta situaci\u00f3n est\u00e1 provocando una caida de la rentabilidad de los bonos gubernamentales, ayer rozaron el 2,10%. La actividad economica, aunque se mantiene en territorio positivo, no alcanza la media historica de crecimiento, alrededor del 3,2% frente al 2% actual. A pesar de los datos expuestos, y con buenos datos de empleo, nuestra opini\u00f3n sobre los tipos reales se mantiene, los consideramos anormalmente bajos como consecuencia de la pol\u00edtica monetaria de los \u00faltimos a\u00f1os.<\/p>\n<p>En Europa las rentabilidades de los bonos de los gobiernos han acompa\u00f1ado el movimiento, que se ha visto reforzado en los paises perif\u00e9ricos y tambi\u00e9n en Francia que sigue eliminando incertidumbres pol\u00edticas.<\/p>\n<p>Durante los \u00faltimos d\u00edas hemos seguido comprando bonos corporativos flotantes y hemos vuelto a incrementar exposici\u00f3n al oro y otros metales preciosos alcanzando el 4% del patrimonio del fondo. <\/p>\n<p>Recuerden, si las letras del tesoro ofrecen rentabilidades negativas: <strong>no hay retorno sin riesgo\u2026<\/strong> y, como siempre \u201ctengan cuidado ah\u00ed fuera\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rafael Pe\u00f1a Gorospe<\/strong><br \/>\nGestor de Adriza Neutral<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acontecimiento m\u00e1s relevante de la \u00faltima semana ha sido la subida de tipos por parte de la Reserva Federal y sus previsiones para reducir su balance, pero lo que nos ha sorprendido ha sido la lectura de los mercados porque parece que los agentes no conf\u00edan en la previsiones del Banco Central.<\/p>\n","protected":false},"author":4,"featured_media":24654,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[405,559,811,2129,2492,2556,3317,5554,5579,5642,5938,6568,6679,6734],"class_list":["post-25810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tressis-gestion","tag-baja-volatilidad","tag-bce","tag-brexit","tag-draghi","tag-estados-unidos","tag-europa","tag-incertidumbre-geopolitica","tag-reformas-fiscales-eeuu","tag-reino-unido","tag-renta-variable","tag-ritmo-alcista","tag-theresa-may","tag-tranquilidad","tag-trump"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adriza Neutral. Comentario semanal (15\/06\/2017)<\/title>\n<meta name=\"description\" content=\"Los recientes datos de inflaci\u00f3n en EEUU no han confirmado la convergencia entre inflaci\u00f3n general y subyacente pronosticados a principios del ejercicio,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adriza Neutral. Comentario semanal (15\/06\/2017)\" \/>\n<meta property=\"og:description\" content=\"Los recientes datos de inflaci\u00f3n en EEUU no han confirmado la convergencia entre inflaci\u00f3n general y subyacente pronosticados a principios del ejercicio,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-15T16:40:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-26T11:31:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/01\/TG_Blog-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"Adriza Neutral. Comentario semanal (15\\\/06\\\/2017)\",\"datePublished\":\"2017-06-15T16:40:57+00:00\",\"dateModified\":\"2023-05-26T11:31:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/TG_Blog-2.jpg\",\"keywords\":[\"baja volatilidad\",\"BCE\",\"Brexit\",\"draghi\",\"Estados Unidos\",\"Europa\",\"incertidumbre geopol\u00edtica\",\"reformas fiscales EEUU\",\"reino unido\",\"renta variable\",\"ritmo alcista\",\"Theresa May\",\"tranquilidad\",\"Trump\"],\"articleSection\":[\"Tressis Gesti\u00f3n\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/\",\"name\":\"Adriza Neutral. Comentario semanal (15\\\/06\\\/2017)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/TG_Blog-2.jpg\",\"datePublished\":\"2017-06-15T16:40:57+00:00\",\"dateModified\":\"2023-05-26T11:31:07+00:00\",\"description\":\"Los recientes datos de inflaci\u00f3n en EEUU no han confirmado la convergencia entre inflaci\u00f3n general y subyacente pronosticados a principios del ejercicio,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/TG_Blog-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/TG_Blog-2.jpg\",\"width\":1100,\"height\":487,\"caption\":\"Adriza Neutral. Comentario semanal (29\\\/05\\\/2018)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/adriza-neutral-comentario-semanal-15062017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"delibilidad d\u00f3lar\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/blog\\\/etiquetas\\\/delibilidad-dolar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adriza Neutral. Comentario semanal (15\\\/06\\\/2017)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adriza Neutral. Comentario semanal (15\/06\/2017)","description":"Los recientes datos de inflaci\u00f3n en EEUU no han confirmado la convergencia entre inflaci\u00f3n general y subyacente pronosticados a principios del ejercicio,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/","og_locale":"ca_ES","og_type":"article","og_title":"Adriza Neutral. Comentario semanal (15\/06\/2017)","og_description":"Los recientes datos de inflaci\u00f3n en EEUU no han confirmado la convergencia entre inflaci\u00f3n general y subyacente pronosticados a principios del ejercicio,","og_url":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2017-06-15T16:40:57+00:00","article_modified_time":"2023-05-26T11:31:07+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/01\/TG_Blog-2.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"Adriza Neutral. Comentario semanal (15\/06\/2017)","datePublished":"2017-06-15T16:40:57+00:00","dateModified":"2023-05-26T11:31:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/01\/TG_Blog-2.jpg","keywords":["baja volatilidad","BCE","Brexit","draghi","Estados Unidos","Europa","incertidumbre geopol\u00edtica","reformas fiscales EEUU","reino unido","renta variable","ritmo alcista","Theresa May","tranquilidad","Trump"],"articleSection":["Tressis Gesti\u00f3n"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/","url":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/","name":"Adriza Neutral. Comentario semanal (15\/06\/2017)","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/01\/TG_Blog-2.jpg","datePublished":"2017-06-15T16:40:57+00:00","dateModified":"2023-05-26T11:31:07+00:00","description":"Los recientes datos de inflaci\u00f3n en EEUU no han confirmado la convergencia entre inflaci\u00f3n general y subyacente pronosticados a principios del ejercicio,","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/01\/TG_Blog-2.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2017\/01\/TG_Blog-2.jpg","width":1100,"height":487,"caption":"Adriza Neutral. Comentario semanal (29\/05\/2018)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/adriza-neutral-comentario-semanal-15062017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"delibilidad d\u00f3lar","item":"https:\/\/www.tressis.com\/blog\/etiquetas\/delibilidad-dolar\/"},{"@type":"ListItem","position":3,"name":"Adriza Neutral. Comentario semanal (15\/06\/2017)"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/25810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=25810"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/25810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/24654"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=25810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=25810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=25810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}