{"id":24163,"date":"2016-11-15T10:44:56","date_gmt":"2016-11-15T09:44:56","guid":{"rendered":"http:\/\/www.tressis.com\/blog\/?p=24163"},"modified":"2016-11-15T10:44:56","modified_gmt":"2016-11-15T09:44:56","slug":"las-consecuencias-las-sentimos-todos","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/","title":{"rendered":"Las consecuencias las sentimos todos"},"content":{"rendered":"<p>Buenos d\u00edas.<\/p>\n<p>Y sigue y sigue y sigue&#8230; Y tendremos reacciones a la elecci\u00f3n de Donald Trump durante a\u00fan mucho tiempo.<!--more--><\/p>\n<p>Porque existe un derecho inalienable a criticar y triturar lo que soberanamente un pa\u00eds y su presidente decidan, y porque como las consecuencias las sentimos todos, nos creemos todav\u00eda con m\u00e1s de ese mismo derecho a atacar.<\/p>\n<p>Pues m\u00e1s nos vale a todos ir acostumbr\u00e1ndonos a la nueva realidad estadounidense, por cierto, muy suavizada respecto a la de la campa\u00f1a electoral. Pero ante la posibilidad de que se cumplan parte de los planes econ\u00f3micos propuestos, los inversores no han dejado de cotizarlos en los mercados, reaccionando a las amenazas de proteccionismo y expansi\u00f3n fiscal masiva &#8230; al menos alguien al fin ha comprendido, aunque sea de aquella manera, que hace falta algo m\u00e1s que un banco central para darle fuerza a la actividad real.<\/p>\n<p>Los mercados de deuda han seguido sufriendo m\u00e1s que nadie este nuevo entorno de mayores expectativas de inflaci\u00f3n con origen m\u00faltiple. Y l\u00f3gicamente la Reserva Federal se tiene que adecuar, o al menos posicionar ante los inversores de cara a un eventual repunte de los precios. Varios de los miembros del FOMC, manteniendo la neutralidad pol\u00edtica del organismo, se expresaron ayer en tal sentido, pues hablaron sin muchos tapujos sobre la necesidad de pensar en mantener los tipos de inter\u00e9s en niveles superiores, o de las maldades y bondades de asuntos tan espinosos como las pol\u00edticas proteccionistas y migratorias.<\/p>\n<p>Europa est\u00e1 mirando con recelo las posibles consecuencias, especialmente en materia de Defensa, aunque tampoco hace falta salirse mucho de por aqu\u00ed para lidiar con problemas de \u00edndole pol\u00edtica. Pero bueno, aunque no sea del todo un consuelo, seguimos creciendo. El PIB alem\u00e1n del tercer trimestre del a\u00f1o ha quedado por debajo de las expectativas por culpa de las partidas de comercio exterior e inversi\u00f3n, pero ha sido capaz de mantener dos d\u00e9cimas de crecimiento gracias a la demanda interna y al gasto p\u00fablico. La producci\u00f3n industrial del conjunto de la zona euro, que ca\u00eda en septiembre, mostraba sin embargo, una sensaci\u00f3n de mejora hacia los pr\u00f3ximos meses.<\/p>\n<p>Buen d\u00eda.<\/p>\n<p><strong>Am\u00edlcar Barrios Vilallonga<\/strong><br \/>\nDirecci\u00f3n de Inversiones<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas. Y sigue y sigue y sigue&#8230; Y tendremos reacciones a la elecci\u00f3n de Donald Trump durante a\u00fan mucho tiempo.<\/p>\n","protected":false},"author":4,"featured_media":24164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[1380,1846,2120,2620,2792,2976,4197,4419,4721,4857,4893,5025,5027,5224,5274,5373,5761,6136,6617],"class_list":["post-24163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morning-meeting","tag-consecuencias","tag-demanda-interna","tag-donald-trump","tag-expansion-fiscal","tag-fomc","tag-gasto-publico","tag-mercados-de-deuda","tag-neutralidad-politica","tag-partidas-de-comercio-exterior","tag-pib-aleman","tag-planes-economicos","tag-politicas-migratorias","tag-politicas-proteccionistas","tag-produccion-industrial","tag-proteccionismo","tag-reaccion-ante-amenazas","tag-reserva-federal","tag-sensacion-de-mejora","tag-tipos-de-interes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las consecuencias las sentimos todos<\/title>\n<meta name=\"description\" content=\"Como las consecuencias las sentimos todos, nos creemos con derecho a criticar, triturar y atacar lo que soberanamente un pa\u00eds y su presidente decidan\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las consecuencias las sentimos todos\" \/>\n<meta property=\"og:description\" content=\"Como las consecuencias las sentimos todos, nos creemos con derecho a criticar, triturar y atacar lo que soberanamente un pa\u00eds y su presidente decidan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-15T09:44:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/11\/20161115_mmv.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"Las consecuencias las sentimos todos\",\"datePublished\":\"2016-11-15T09:44:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/\"},\"wordCount\":396,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161115_mmv.jpg\",\"keywords\":[\"consecuencias\",\"demanda interna\",\"Donald Trump\",\"expansi\u00f3n fiscal\",\"FOMC\",\"gasto p\u00fablico\",\"mercados de deuda\",\"neutralidad pol\u00edtica\",\"partidas de comercio exterior\",\"PIB alem\u00e1n\",\"planes econ\u00f3micos\",\"pol\u00edticas migratorias\",\"pol\u00edticas proteccionistas\",\"producci\u00f3n industrial\",\"proteccionismo\",\"reacci\u00f3n ante amenazas\",\"Reserva Federal\",\"sensaci\u00f3n de mejora\",\"tipos de inter\u00e9s\"],\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/\",\"name\":\"Las consecuencias las sentimos todos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161115_mmv.jpg\",\"datePublished\":\"2016-11-15T09:44:56+00:00\",\"description\":\"Como las consecuencias las sentimos todos, nos creemos con derecho a criticar, triturar y atacar lo que soberanamente un pa\u00eds y su presidente decidan\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161115_mmv.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/20161115_mmv.jpg\",\"width\":1100,\"height\":487,\"caption\":\"Las consecuencias las sentimos todos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/las-consecuencias-las-sentimos-todos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las consecuencias las sentimos todos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las consecuencias las sentimos todos","description":"Como las consecuencias las sentimos todos, nos creemos con derecho a criticar, triturar y atacar lo que soberanamente un pa\u00eds y su presidente decidan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/","og_locale":"ca_ES","og_type":"article","og_title":"Las consecuencias las sentimos todos","og_description":"Como las consecuencias las sentimos todos, nos creemos con derecho a criticar, triturar y atacar lo que soberanamente un pa\u00eds y su presidente decidan","og_url":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2016-11-15T09:44:56+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/11\/20161115_mmv.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"Las consecuencias las sentimos todos","datePublished":"2016-11-15T09:44:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/"},"wordCount":396,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/11\/20161115_mmv.jpg","keywords":["consecuencias","demanda interna","Donald Trump","expansi\u00f3n fiscal","FOMC","gasto p\u00fablico","mercados de deuda","neutralidad pol\u00edtica","partidas de comercio exterior","PIB alem\u00e1n","planes econ\u00f3micos","pol\u00edticas migratorias","pol\u00edticas proteccionistas","producci\u00f3n industrial","proteccionismo","reacci\u00f3n ante amenazas","Reserva Federal","sensaci\u00f3n de mejora","tipos de inter\u00e9s"],"articleSection":["Morning meeting"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/","url":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/","name":"Las consecuencias las sentimos todos","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/11\/20161115_mmv.jpg","datePublished":"2016-11-15T09:44:56+00:00","description":"Como las consecuencias las sentimos todos, nos creemos con derecho a criticar, triturar y atacar lo que soberanamente un pa\u00eds y su presidente decidan","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/11\/20161115_mmv.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/11\/20161115_mmv.jpg","width":1100,"height":487,"caption":"Las consecuencias las sentimos todos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/las-consecuencias-las-sentimos-todos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Las consecuencias las sentimos todos"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/24163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=24163"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/24163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/24164"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=24163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=24163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=24163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}