{"id":24065,"date":"2016-11-02T10:15:24","date_gmt":"2016-11-02T10:15:24","guid":{"rendered":"http:\/\/www.tressis.com\/blog\/?p=24065"},"modified":"2023-05-26T13:18:32","modified_gmt":"2023-05-26T11:18:32","slug":"imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/","title":{"rendered":"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF"},"content":{"rendered":"<p>La volatilidad en los mercados unida con la inestabilidad pol\u00edtica ha dado como resultado un a\u00f1o ciertamente dif\u00edcil para los gestores de patrimonio.<!--more--><\/p>\n<p>Por ello, hemos cre\u00eddo conveniente recordar un aspecto como es el de las p\u00e9rdidas patrimoniales, que si bien no es plato de buen gusto para un inversor, se constituye como un punto de gran importancia a la hora de planificar el resultado financiero-fiscal de una persona.<\/p>\n<p>Son ganancias y p\u00e9rdidas patrimoniales las variaciones en el valor del patrimonio del contribuyente que se pongan de manifiesto con ocasi\u00f3n de cualquier alteraci\u00f3n en la composici\u00f3n de aqu\u00e9l.<\/p>\n<p>En este sentido, es fundamental para el contribuyente conocer el momento y la forma de integrar dichas p\u00e9rdidas patrimoniales en su patrimonio a los efectos de planificar correctamente su futuro pago del impuesto.<\/p>\n<p>Teniendo en cuenta el momento del a\u00f1o en el que nos encontramos \u2014pr\u00f3ximo cierre del ejercicio econ\u00f3mico 2016\u2014 desde Tressis creemos conveniente repasar los se\u00f1alados conceptos.<\/p>\n<p><strong>Criterios de imputaci\u00f3n de las p\u00e9rdidas patrimoniales:<\/strong><\/p>\n<p>Como regla general, el art. 14 de la Ley del IRPF establece que los ingresos y gastos que determinan las ganancias y p\u00e9rdidas patrimoniales se imputar\u00e1n al per\u00edodo impositivo en que tenga lugar la alteraci\u00f3n patrimonial. No obstante lo anterior, existen situaciones en las que no est\u00e1 tan claro cu\u00e1ndo se produce dicha alternaci\u00f3n patrimonial. As\u00ed, por ejemplo, nos encontramos con los siguientes casos:<\/p>\n<p>\u2022<strong> Acciones suspendidas de cotizaci\u00f3n. Cu\u00e1ndo me puedo integrar una p\u00e9rdida fiscal. <\/strong><\/p>\n<p>De acuerdo al criterio de la Direcci\u00f3n General de Tributos (V3166-15), la suspensi\u00f3n de cotizaci\u00f3n de las acciones de una sociedad cotizada no comporta de forma autom\u00e1tica la existencia de una p\u00e9rdida patrimonial para los socios, sino que es necesaria la disoluci\u00f3n y liquidaci\u00f3n de la sociedad.<\/p>\n<p>En conclusi\u00f3n, para que el contribuyente pueda computarse una p\u00e9rdida patrimonial en los t\u00e9rminos establecidos en la Ley, debe previamente procederse a la disoluci\u00f3n y liquidaci\u00f3n de la sociedad, siendo el per\u00edodo impositivo en el que se produzca la liquidaci\u00f3n cuando se considera producida la alteraci\u00f3n patrimonial determinante, en su caso, de una p\u00e9rdida patrimonial para el accionista.<\/p>\n<p>\u2022 <strong>Concurso de acreedores. Cu\u00e1ndo me integro la p\u00e9rdida patrimonial.<\/strong><\/p>\n<p>De acuerdo al criterio de la Direcci\u00f3n General de Tributos (V2656-15) la falta de pago por un deudor a su acreedor del importe adeudado no constituye de forma autom\u00e1tica la existencia de una p\u00e9rdida patrimonial. As\u00ed las cosas, el criterio que sobre el particular ven\u00eda manteniendo la Direcci\u00f3n General de Tributos era que s\u00f3lo cuando ese derecho de cr\u00e9dito <strong>resultase judicialmente incobrable<\/strong> ser\u00eda cuando tendr\u00eda sus efectos en la liquidaci\u00f3n del IRPF por el importe no cobrado.<\/p>\n<p>No obstante lo anterior, procede se\u00f1alar que a partir del 1 de enero de 2015, se introduce en la normativa del impuesto una regla especial de imputaci\u00f3n temporal para estos supuestos de cr\u00e9ditos no cobrados. As\u00ed, la letra k) del art\u00edculo 14.2 de la Ley de IRPF, determina lo siguiente:<\/p>\n<p><i>\u201cLas p\u00e9rdidas patrimoniales derivadas de cr\u00e9ditos vencidos y no cobrados podr\u00e1n imputarse al per\u00edodo impositivo en que concurra alguna de las siguientes circunstancias:<\/i><\/p>\n<p><i>1.\u00ba Que adquiera eficacia una quita establecida en un acuerdo de refinanciaci\u00f3n judicialmente homologable a los que se refiere el art\u00edculo 71 bis y la disposici\u00f3n adicional cuarta de la Ley 22\/2003, de 9 de julio, Concursal, o en un acuerdo extrajudicial de pagos a los cuales se refiere el T\u00edtulo X de la misma Ley.<\/i><\/p>\n<p><i>2.\u00ba Que, encontr\u00e1ndose el deudor en situaci\u00f3n de concurso, adquiera eficacia el convenio en el que se acuerde una quita en el importe del cr\u00e9dito conforme a lo dispuesto en el art\u00edculo 133 de la Ley 22\/2003, de 9 de julio, Concursal, en cuyo caso la p\u00e9rdida se computar\u00e1 por la cuant\u00eda de la quita.<\/i><\/p>\n<p><i>3.\u00ba Que se cumpla el plazo de un a\u00f1o desde el inicio del procedimiento judicial distinto de los de concurso que tenga por objeto la ejecuci\u00f3n del cr\u00e9dito sin que este haya sido satisfecho.<\/i><\/p>\n<p><i>Cuando el cr\u00e9dito fuera cobrado con posterioridad al c\u00f3mputo de la p\u00e9rdida patrimonial a que se refiere esta letra k), se imputar\u00e1 una ganancia patrimonial por el importe cobrado en el per\u00edodo impositivo en que se produzca dicho cobro\u201d.<\/i><\/p>\n<p>Dicho lo anterior, podr\u00e1 entenderse producida una p\u00e9rdida patrimonial cuando concurran las circunstancias establecidas en el n\u00famero 2\u00ba de la letra k) del art\u00edculo 14.2.<\/p>\n<p>Por otra parte, respecto a la integraci\u00f3n de esta p\u00e9rdida en la base imponible del impuesto cabe se\u00f1alar que el hecho de proceder de una transmisi\u00f3n de elementos patrimoniales conlleva su consideraci\u00f3n como renta del ahorro.<\/p>\n<p>En conclusi\u00f3n, el cliente en estos casos solo podr\u00e1 imputarse la p\u00e9rdida patrimonial en el momento en que adquiera eficacia el convenio en el que se acuerde una quita en el importe del cr\u00e9dito.<\/p>\n<p><strong>\u2022 Renuncia al cobro de derechos de cr\u00e9dito. Cu\u00e1ndo me puedo imputar las p\u00e9rdidas patrimoniales.<\/strong><\/p>\n<p>El art\u00edculo 33.5.c) de la LIRPF dispone que no se computar\u00e1n como p\u00e9rdidas patrimoniales las debidas a transmisiones lucrativas por actos <i>inter vivos<\/i> o a liberalidades. Por lo tanto, debe tenerse en cuenta que el contribuyente que renuncie al cobro de un derecho de cr\u00e9dito no podr\u00e1 imputarse dicha p\u00e9rdida patrimonial en su IRPF.<\/p>\n<p><strong>Integraci\u00f3n de las p\u00e9rdidas patrimoniales:<\/strong><\/p>\n<p>El art. 47 de la LIRPF, establece que:<\/p>\n<p><i>\u201cPara el c\u00e1lculo de la base imponible, las cuant\u00edas positivas o negativas de las rentas del contribuyente se integrar\u00e1n y compensar\u00e1n de acuerdo con lo previsto en esta Ley\u201d.<\/i><\/p>\n<p>A su vez, el art. 49 de la LIRPF, establece que:<\/p>\n<p><i>1. La base imponible del ahorro estar\u00e1 constituida por el saldo positivo de sumar los siguientes saldos:<\/i><\/p>\n<p><i>a) El saldo positivo resultante de integrar y compensar, exclusivamente entre s\u00ed, en cada per\u00edodo impositivo, los rendimientos a que se refiere el art\u00edculo 46 de esta Ley.<\/i><\/p>\n<p><i>Si el resultado de la integraci\u00f3n y compensaci\u00f3n a que se refiere este p\u00e1rrafo arrojase saldo negativo, su importe se compensar\u00e1 con el saldo positivo de las rentas previstas en la letra b) de este apartado, obtenido en el mismo per\u00edodo impositivo, con el l\u00edmite del 25 por ciento de dicho saldo positivo.<\/i><\/p>\n<p><i>Si tras dicha compensaci\u00f3n quedase saldo negativo, su importe se compensar\u00e1 en los cuatro a\u00f1os siguientes en el mismo orden establecido en los p\u00e1rrafos anteriores.<\/i><\/p>\n<p><i>b) El saldo positivo resultante de integrar y compensar, exclusivamente entre s\u00ed, en cada per\u00edodo impositivo, las ganancias y p\u00e9rdidas patrimoniales obtenidas en el mismo a que se refiere el art\u00edculo 46 de esta Ley.<\/i><\/p>\n<p><i>Si el resultado de la integraci\u00f3n y compensaci\u00f3n a que se refiere este p\u00e1rrafo arrojase saldo negativo, su importe se compensar\u00e1 con el saldo positivo de las rentas previstas en la letra a) de este apartado, obtenido en el mismo per\u00edodo impositivo, con el l\u00edmite del 25 por ciento de dicho saldo positivo.<\/i><\/p>\n<p><i>Si tras dicha compensaci\u00f3n quedase saldo negativo, su importe se compensar\u00e1 en los cuatro a\u00f1os siguientes en el mismo orden establecido en los p\u00e1rrafos anteriores.<\/i><\/p>\n<p>Lo anterior supone que:<\/p>\n<p>\u2022 El contribuyente deber\u00e1 tener en cuenta que existen tres niveles de compensaci\u00f3n en el IRPF.<\/p>\n<p>&#8211; Primer nivel de compensaci\u00f3n: integraci\u00f3n y compensaci\u00f3n de las alteraciones de patrimonio provenientes de activos financieros con la misma calificaci\u00f3n fiscal.<\/p>\n<p>&#8211; Segundo nivel de compensaci\u00f3n: En caso de que dicha integraci\u00f3n y compensaci\u00f3n arrojara un saldo negativo, el contribuyente podr\u00e1 compensar el importe de dichas p\u00e9rdidas con el resultado positivo de las otras rentas previstas en la base imponible del ahorro, con el l\u00edmite del 15% de dicho saldo positivo.<\/p>\n<p>&#8211; Tercer nivel de compensaci\u00f3n: Si tras dicha compensaci\u00f3n quedase saldo negativo, su importe se compensar\u00e1 en los cuatro a\u00f1os siguientes.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-24066 aligncenter\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/post-lina.jpg\" alt=\"\" width=\"624\" height=\"414\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/post-lina.jpg 624w, https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/post-lina-300x199.jpg 300w\" sizes=\"(max-width: 624px) 100vw, 624px\" \/><\/p>\n<p>\u2022 El contribuyente, a la hora de planificar correctamente lo anterior, deber\u00e1 tener en cuenta que las p\u00e9rdidas patrimoniales suponen la posibilidad de disminuir su factura fiscal, por lo que:<\/p>\n<p>&#8211; Deber\u00e1 antes de finalizar el a\u00f1o planificar correctamente con su asesor financiero la posibilidad y conveniencia de generar las mismas.<\/p>\n<p>&#8211; Deber\u00e1 llevar un registro actualizado de las p\u00e9rdidas generadas en ejercicios anteriores. Ha de tenerse en cuenta que la Agencia Tributaria no comunica a los contribuyentes el saldo fiscal pendiente de compensaci\u00f3n, por lo que es el contribuyente el que deber\u00e1 tener un registro del mismo.<\/p>\n<p><strong><br \/>\nLina Marcela Guerra<\/strong><br \/>\nDirectora Planificaci\u00f3n Patrimonial y Fiscal<\/p>\n<h6>El contenido de este documento no constituye asesoramiento, sino que es meramente divulgativo. En particular, cualquier decisi\u00f3n o actuaci\u00f3n relacionada con el contenido de esta alerta deber\u00eda ser objeto de an\u00e1lisis especifico y adecuado a la situaci\u00f3n particular de que se trate<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La volatilidad en los mercados unida con la inestabilidad pol\u00edtica ha dado como resultado un a\u00f1o ciertamente dif\u00edcil para los gestores de patrimonio.<\/p>\n","protected":false},"author":4,"featured_media":24071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8561],"tags":[166,238,543,1345,1454,1461,1607,1614,1988,2048,2065,2231,2233,2952,2953,3032,3271,3275,3304,3305,3449,3502,3520,3521,3525,3529,3679,3747,3748,3833,4187,4665,4781,4785,4903,4907,5323,5534,5596,5613,5720,5997,6241,6920],"class_list":["post-24065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiscalidad","tag-alteracion-patrimonial","tag-antes-finalizar-ano","tag-base-imponible","tag-concurso-acreedores","tag-contribuyente","tag-convenio","tag-credito","tag-creditos-vencidos","tag-deudor","tag-direccion-general-de-tributos","tag-disolucion-y-liquidacion-de-sociedad","tag-ejercicio-economico-2016","tag-ejercicios-anteriores","tag-ganancias-y-perdidas-patrimoniales","tag-ganancias-y-perdidas-transmisiones","tag-gestores-de-patrimonio","tag-importe-del-credito","tag-impuesto","tag-imputacion","tag-imputacion-temporal","tag-inestabilidad-politica","tag-ingresos-y-gastos","tag-integracicon","tag-integracion","tag-integrar-y-compensar","tag-inter-vivos","tag-irpf","tag-judicial","tag-judicialmente-incobrable","tag-liberalidades","tag-mercados","tag-pago-del-impuesto","tag-perdida-fiscal","tag-perdidas-patrimoniales","tag-planificar","tag-planificar-resultado-financiero-fiscal","tag-quita","tag-refinanciacion","tag-rendimiento-de-capital-mobiliario","tag-renta-del-ahorro","tag-renuncia-al-cobro-derechos-credito","tag-saldo-positivo","tag-sociedad-cotizada","tag-volatilidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF<\/title>\n<meta name=\"description\" content=\"Hemos cre\u00eddo conveniente recordar un aspecto como el de las p\u00e9rdidas patrimoniales, que para un inversor, se constituye como un punto de gran importancia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF\" \/>\n<meta property=\"og:description\" content=\"Hemos cre\u00eddo conveniente recordar un aspecto como el de las p\u00e9rdidas patrimoniales, que para un inversor, se constituye como un punto de gran importancia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-02T10:15:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-26T11:18:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/20161031_post.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/\"},\"author\":{\"name\":\"Lola\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\"},\"headline\":\"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF\",\"datePublished\":\"2016-11-02T10:15:24+00:00\",\"dateModified\":\"2023-05-26T11:18:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/\"},\"wordCount\":1536,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/20161031_post.jpg\",\"keywords\":[\"alteraci\u00f3n patrimonial\",\"antes finalizar a\u00f1o\",\"base imponible\",\"concurso acreedores\",\"contribuyente\",\"convenio\",\"cr\u00e9dito\",\"cr\u00e9ditos vencidos\",\"deudor\",\"Direcci\u00f3n General de Tributos\",\"disoluci\u00f3n y liquidaci\u00f3n de sociedad\",\"ejercicio econ\u00f3mico 2016\",\"ejercicios anteriores\",\"ganancias y p\u00e9rdidas patrimoniales\",\"ganancias y p\u00e9rdidas transmisiones\",\"gestores de patrimonio\",\"importe del cr\u00e9dito\",\"impuesto\",\"imputaci\u00f3n\",\"imputaci\u00f3n temporal\",\"inestabilidad pol\u00edtica\",\"ingresos y gastos\",\"integraci\u00e7on\",\"integraci\u00f3n\",\"integrar y compensar\",\"inter vivos\",\"IRPF\",\"judicial\",\"judicialmente incobrable\",\"liberalidades\",\"mercados\",\"pago del impuesto\",\"p\u00e9rdida fiscal\",\"p\u00e9rdidas patrimoniales\",\"planificar\",\"planificar resultado financiero-fiscal\",\"quita\",\"refinanciaci\u00f3n\",\"rendimiento de capital mobiliario\",\"renta del ahorro\",\"renuncia al cobro derechos cr\u00e9dito\",\"saldo positivo\",\"sociedad cotizada\",\"volatilidad\"],\"articleSection\":[\"Fiscalidad\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/\",\"name\":\"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/20161031_post.jpg\",\"datePublished\":\"2016-11-02T10:15:24+00:00\",\"dateModified\":\"2023-05-26T11:18:32+00:00\",\"description\":\"Hemos cre\u00eddo conveniente recordar un aspecto como el de las p\u00e9rdidas patrimoniales, que para un inversor, se constituye como un punto de gran importancia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/20161031_post.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/20161031_post.jpg\",\"width\":1100,\"height\":487,\"caption\":\"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"agregado\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/blog\\\/etiquetas\\\/agregado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/b833c1d724d8764920b6d6852c70584e\",\"name\":\"Lola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g\",\"caption\":\"Lola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF","description":"Hemos cre\u00eddo conveniente recordar un aspecto como el de las p\u00e9rdidas patrimoniales, que para un inversor, se constituye como un punto de gran importancia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/","og_locale":"ca_ES","og_type":"article","og_title":"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF","og_description":"Hemos cre\u00eddo conveniente recordar un aspecto como el de las p\u00e9rdidas patrimoniales, que para un inversor, se constituye como un punto de gran importancia","og_url":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2016-11-02T10:15:24+00:00","article_modified_time":"2023-05-26T11:18:32+00:00","og_image":[{"width":1100,"height":487,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/20161031_post.jpg","type":"image\/jpeg"}],"author":"Lola","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Lola","Temps estimat de lectura":"8 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/"},"author":{"name":"Lola","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e"},"headline":"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF","datePublished":"2016-11-02T10:15:24+00:00","dateModified":"2023-05-26T11:18:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/"},"wordCount":1536,"commentCount":0,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/20161031_post.jpg","keywords":["alteraci\u00f3n patrimonial","antes finalizar a\u00f1o","base imponible","concurso acreedores","contribuyente","convenio","cr\u00e9dito","cr\u00e9ditos vencidos","deudor","Direcci\u00f3n General de Tributos","disoluci\u00f3n y liquidaci\u00f3n de sociedad","ejercicio econ\u00f3mico 2016","ejercicios anteriores","ganancias y p\u00e9rdidas patrimoniales","ganancias y p\u00e9rdidas transmisiones","gestores de patrimonio","importe del cr\u00e9dito","impuesto","imputaci\u00f3n","imputaci\u00f3n temporal","inestabilidad pol\u00edtica","ingresos y gastos","integraci\u00e7on","integraci\u00f3n","integrar y compensar","inter vivos","IRPF","judicial","judicialmente incobrable","liberalidades","mercados","pago del impuesto","p\u00e9rdida fiscal","p\u00e9rdidas patrimoniales","planificar","planificar resultado financiero-fiscal","quita","refinanciaci\u00f3n","rendimiento de capital mobiliario","renta del ahorro","renuncia al cobro derechos cr\u00e9dito","saldo positivo","sociedad cotizada","volatilidad"],"articleSection":["Fiscalidad"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/","url":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/","name":"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/20161031_post.jpg","datePublished":"2016-11-02T10:15:24+00:00","dateModified":"2023-05-26T11:18:32+00:00","description":"Hemos cre\u00eddo conveniente recordar un aspecto como el de las p\u00e9rdidas patrimoniales, que para un inversor, se constituye como un punto de gran importancia","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/20161031_post.jpg","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2016\/10\/20161031_post.jpg","width":1100,"height":487,"caption":"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/imputacion-e-integracion-perdidas-patrimoniales-en-el-irpf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"agregado","item":"https:\/\/www.tressis.com\/blog\/etiquetas\/agregado\/"},{"@type":"ListItem","position":3,"name":"Imputaci\u00f3n e integraci\u00f3n de p\u00e9rdidas patrimoniales en el IRPF"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/b833c1d724d8764920b6d6852c70584e","name":"Lola","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/05e646486b23ff45df9649110609c7e31b8c4a3e2821caa23d6317f405e0c51d?s=96&d=mm&r=g","caption":"Lola"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/24065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=24065"}],"version-history":[{"count":0,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/24065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/24071"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=24065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=24065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=24065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}