{"id":115275,"date":"2026-01-27T08:54:01","date_gmt":"2026-01-27T07:54:01","guid":{"rendered":"https:\/\/www.tressis.com\/?p=115275"},"modified":"2026-01-27T10:26:31","modified_gmt":"2026-01-27T09:26:31","slug":"ee-uu-crece-al-44","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/","title":{"rendered":"EE.UU. crece al 4,4%"},"content":{"rendered":"<p>En el plano macroecon\u00f3mico, los datos siguen dibujando un escenario constructivo en EE.UU. Ayer, la revisi\u00f3n al alza del crecimiento del PIB del tercer trimestre hasta el 4,4% anual reforz\u00f3 la idea de <strong>una econom\u00eda que mantiene un crecimiento elevado<\/strong>, apoyado en el consumo y la inversi\u00f3n. En cuanto a la inflaci\u00f3n, los datos retrasados del deflactor del consumo personal confirmaron que tanto la tasa general como la subyacente permanecen en el 2,8%, lo que sugiere que <strong>el proceso de desinflaci\u00f3n contin\u00faa<\/strong>, pero de forma lenta y sin dar a\u00fan margen claro para seguir con la bajada de tipos. Por otro lado, en la zona euro, la revisi\u00f3n a la baja del IPC de diciembre hasta el 1,9%, con una subyacente del 2,3%, apunta a una moderaci\u00f3n m\u00e1s evidente de las presiones de precios, aunque con un crecimiento econ\u00f3mico que sigue siendo d\u00e9bil y muy desigual entre pa\u00edses.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center; margin-bottom: 10px;\"><a \nhref=\"https:\/\/www.tressis.com\/tressis-vision\/?utm_source=web_publica&amp;utm_medium=direct&amp;utm_campaign=descarga_paper&amp;utm_term=tressisvision&amp;utm_content=blog_MMV\" \ntarget=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" class=\"aligncenter wp-image-67199 size-full\" \nsrc=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg\" \nalt=\"Informe mensual - Tressis visi\u00f3n\" width=\"800\" height=\"354\" style=\"aspect-ratio: 400 \/ 177;\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg 800w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-300x133.jpg 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-768x340.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>Asimismo, <strong>en el mercado de renta variable este contexto reflej\u00f3 un comportamiento dispar<\/strong>. Estados Unidos mostr\u00f3 una mayor resiliencia. El Nasdaq subi\u00f3 un 0,89% mientras el que el S&#038;P500 avanz\u00f3 un 0,5%, impulsados por una temporada de resultados que, en conjunto, est\u00e1 superando las expectativas y mostrando crecimientos s\u00f3lidos de beneficios. Hasta ahora, las 64 compa\u00f1\u00edas del S&#038;P 500 que han publicado resultados presentan un <strong>crecimiento medio de beneficios del 17,6%<\/strong>. Sin embargo, en Europa, la sesi\u00f3n estuvo m\u00e1s condicionada por el aumento de la incertidumbre pol\u00edtica, especialmente en Francia (CAC -0,15%), tras el uso de mecanismos extraordinarios para sacar adelante los presupuestos de 2026. Este factor volvi\u00f3 a pesar sobre el sentimiento inversor y limit\u00f3 el comportamiento de los principales \u00edndices (Euro Stoxx 50 +0,16%), que aun as\u00ed mantienen un balance positivo en lo que va de a\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center; margin-bottom: 10px;\"><img decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image-20260127.webp\" width=\"1080\" height=\"340\" alt=\"Image 01 - 27\/01\/2026\" class=\"wp-image-115285\" style=\"aspect-ratio: 54 \/ 17;\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image-20260127.webp 1080w, https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image-20260127-300x94.webp 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image-20260127-1024x322.webp 1024w, https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image-20260127-768x242.webp 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div>\n<p style=\"text-align: center; margin:20px auto;\" class=\"smallPie\">Fuente: Bloomberg.<\/p>\n<p>&nbsp;<\/p>\n<p>La sesi\u00f3n en los mercados de <strong>renta fija transcurri\u00f3 de forma contenida en Estados Unidos<\/strong>, con el bono americano a diez a\u00f1os estabilizado en torno al 4,2%, mientras que Jap\u00f3n vuelve a ganar protagonismo. El mercado de bonos del Estado de Jap\u00f3n ha dejado de actuar como ancla de estabilidad tras el fuerte repunte de las rentabilidades, con el bono a treinta a\u00f1os por encima del 3%. <strong>El fin de los tipos negativos, una inflaci\u00f3n m\u00e1s persistente y un giro fiscal claramente expansivo<\/strong> explican este movimiento. El principal riesgo es que una mayor volatilidad y una eventual repatriaci\u00f3n de capitales japoneses sigan presionando al alza las curvas de deuda globales.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center; margin-bottom: 30px;\"><img decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image02-20260127.webp\" width=\"880\" height=\"600\" alt=\"Image 02 - 27\/01\/2026\" class=\"wp-image-115283\" style=\"aspect-ratio: 22 \/ 15;\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image02-20260127.webp 880w, https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image02-20260127-300x205.webp 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image02-20260127-768x524.webp 768w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><\/div>\n<div style=\"text-align: center; margin-bottom: 10px;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image03-20260127.webp\" width=\"900\" height=\"600\" alt=\"Image 03 - 27\/01\/2026\" class=\"wp-image-115281\" style=\"aspect-ratio: 3 \/ 2;\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image03-20260127.webp 900w, https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image03-20260127-300x200.webp 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image03-20260127-768x512.webp 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/div>\n<p style=\"text-align: center; margin:20px auto;\" class=\"smallPie\">Fuente: Bloomberg.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>La plata toca los 115 d\u00f3lares antes de corregir<\/strong><\/h2>\n<p>Las materias primas se comportaron forma dispar. El petr\u00f3leo corrigi\u00f3 ligeramente: el brent cay\u00f3 en torno a un 0,5% hasta los 65,5 d\u00f3lares por barril, aunque mantiene una revalorizaci\u00f3n acumulada del 7,6% en lo que va de a\u00f1o. Por su parte, el gas contin\u00faa una fuerte tendencia alcista y acumula ya <strong>una subida cercana al 80% en el a\u00f1o<\/strong>. Sin embargo, los verdaderos protagonistas fueron los metales preciosos, con la plata liderando el movimiento. El metal experiment\u00f3 una fuerte volatilidad, super\u00f3 los 115 d\u00f3lares por onza antes de corregir hasta los 103 d\u00f3lares. Esta presi\u00f3n al alza se ve reforzada por la fuerte demanda f\u00edsica en Asia, especialmente en China, donde la plata cotiza actualmente con prima frente a mercados occidentales por su utilizaci\u00f3n como <strong>cobertura ante la debilidad del yuan y su elevado uso industrial<\/strong>, dando soporte al precio.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center; margin-bottom: 30px;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image04-01-20260127.webp\" width=\"290\" height=\"290\" alt=\"Image 04 - 27\/01\/2026\" class=\"wp-image-115279\" style=\"aspect-ratio: 1 \/ 1;\" \/><\/div>\n<div style=\"text-align: center; margin-bottom: 10px;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/image04-02-20260127.webp\" width=\"550\" height=\"300\" alt=\"Image 05 - 27\/01\/2026\" class=\"wp-image-115279\" style=\"aspect-ratio: 11 \/ 6;\" \/><\/div>\n<p style=\"text-align: center; margin:20px auto;\" class=\"smallPie\">Fuente: CompaniesMarketCap.<\/p>\n<p>&nbsp;<\/p>\n<p>De cara a las pr\u00f3ximas jornadas, el foco del mercado estar\u00e1 en <strong>la reuni\u00f3n de la Reserva Federal de este mi\u00e9rcoles<\/strong>. No se esperan cambios en los tipos de inter\u00e9s, pero s\u00ed un mensaje relevante sobre el grado de consenso interno y el calendario de posibles movimientos para los pr\u00f3ximos meses. A ello se suma una semana intensa en resultados empresariales, especialmente en el sector tecnol\u00f3gico, que permitir\u00e1 evaluar <strong>hasta qu\u00e9 punto el impulso ligado a la inteligencia artificial sigue traslad\u00e1ndose al crecimiento y los m\u00e1rgenes<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Feliz martes.<\/p>\n<p>&nbsp;<\/p>\n<p><center><strong>Urko Rosel de la Rocha<\/strong><br \/>\nAnalista<\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el plano macroecon\u00f3mico, los datos siguen dibujando un escenario constructivo en EE.UU. Ayer, la revisi\u00f3n al alza del crecimiento del PIB del tercer trimestre hasta el 4,4% anual reforz\u00f3 la idea de una econom\u00eda que mantiene un crecimiento elevado, apoyado en el consumo y la inversi\u00f3n. En cuanto a la inflaci\u00f3n, los datos retrasados [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":115287,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[],"class_list":["post-115275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morning-meeting"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EE.UU. crece al 4,4%<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. crece al 4,4%\" \/>\n<meta property=\"og:description\" content=\"En el plano macroecon\u00f3mico, los datos siguen dibujando un escenario constructivo en EE.UU. Ayer, la revisi\u00f3n al alza del crecimiento del PIB del tercer trimestre hasta el 4,4% anual reforz\u00f3 la idea de una econom\u00eda que mantiene un crecimiento elevado, apoyado en el consumo y la inversi\u00f3n. En cuanto a la inflaci\u00f3n, los datos retrasados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-27T07:54:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T09:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/eeuu-crece.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Armando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Armando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/\"},\"author\":{\"name\":\"Armando\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\"},\"headline\":\"EE.UU. crece al 4,4%\",\"datePublished\":\"2026-01-27T07:54:01+00:00\",\"dateModified\":\"2026-01-27T09:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/\"},\"wordCount\":690,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/eeuu-crece.webp\",\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/\",\"name\":\"EE.UU. crece al 4,4%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/eeuu-crece.webp\",\"datePublished\":\"2026-01-27T07:54:01+00:00\",\"dateModified\":\"2026-01-27T09:26:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/eeuu-crece.webp\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/eeuu-crece.webp\",\"width\":1200,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/ee-uu-crece-al-44\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morning meeting\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/morning-meeting-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EE.UU. crece al 4,4%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\",\"name\":\"Armando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"caption\":\"Armando\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. crece al 4,4%","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"ca_ES","og_type":"article","og_title":"EE.UU. crece al 4,4%","og_description":"En el plano macroecon\u00f3mico, los datos siguen dibujando un escenario constructivo en EE.UU. Ayer, la revisi\u00f3n al alza del crecimiento del PIB del tercer trimestre hasta el 4,4% anual reforz\u00f3 la idea de una econom\u00eda que mantiene un crecimiento elevado, apoyado en el consumo y la inversi\u00f3n. En cuanto a la inflaci\u00f3n, los datos retrasados [&hellip;]","og_url":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2026-01-27T07:54:01+00:00","article_modified_time":"2026-01-27T09:26:31+00:00","og_image":[{"width":1200,"height":531,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/eeuu-crece.webp","type":"image\/webp"}],"author":"Armando","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Armando","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/"},"author":{"name":"Armando","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae"},"headline":"EE.UU. crece al 4,4%","datePublished":"2026-01-27T07:54:01+00:00","dateModified":"2026-01-27T09:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/"},"wordCount":690,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/eeuu-crece.webp","articleSection":["Morning meeting"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/","url":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/","name":"EE.UU. crece al 4,4%","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/eeuu-crece.webp","datePublished":"2026-01-27T07:54:01+00:00","dateModified":"2026-01-27T09:26:31+00:00","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/eeuu-crece.webp","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2026\/01\/eeuu-crece.webp","width":1200,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/ee-uu-crece-al-44\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Morning meeting","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/morning-meeting-ca\/"},{"@type":"ListItem","position":3,"name":"EE.UU. crece al 4,4%"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae","name":"Armando","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","caption":"Armando"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/115275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=115275"}],"version-history":[{"count":3,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/115275\/revisions"}],"predecessor-version":[{"id":115301,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/115275\/revisions\/115301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/115287"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=115275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=115275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=115275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}