{"id":113386,"date":"2025-11-14T12:39:15","date_gmt":"2025-11-14T11:39:15","guid":{"rendered":"https:\/\/www.tressis.com\/?p=113386"},"modified":"2025-11-14T16:05:02","modified_gmt":"2025-11-14T15:05:02","slug":"aversion-riesgo-ante-dudas","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/","title":{"rendered":"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas"},"content":{"rendered":"<p>La sesi\u00f3n de ayer dej\u00f3 un tono claramente negativo en los mercados. En Europa, las principales bolsas cerraron en rojo: el DAX lider\u00f3 las ca\u00eddas con un -1,39%, seguido del FTSE 100 (-1,09%), el IBEX 35 (-0,23%) y el CAC 40 (-0,11%). El \u00fanico sector que logr\u00f3 escapar a las ventas fue el inmobiliario (+0,11%), mientras que los negocios industriales encabezaron los retrocesos con un -1,66%, tras peores resultados empresariales de Siemens AG. Al otro lado del Atl\u00e1ntico, el color dominante tambi\u00e9n fue el rojo: el S&#038;P 500 cay\u00f3 un 1,66%, el Dow Jones un 1,65% y el Nasdaq un 2,29%. Las fuertes correcciones en consumo discrecional y tecnolog\u00eda presionaron al mercado, con Tesla (-6,12%) y Amazon (-2,71%) a la cabeza y, una ca\u00edda generalizada de semiconductores (-3,65%) liderada por Nvidia (-3,58%). La energ\u00eda fue el \u00fanico sector estadounidense que termin\u00f3 en positivo (+0,31%).<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Instrumentos de deuda<\/strong><\/h2>\n<p>En renta fija, tampoco hubo refugio. Las curvas europeas y la estadounidense presentaron repuntes en las rentabilidades exigidas: el <em>bund<\/em> alem\u00e1n subi\u00f3 4,4 p.b. hasta el 2,69%, mientras que el <em>treasury<\/em> a diez a\u00f1os avanz\u00f3 3 p.b. hasta el 4,09%. Los diferenciales de cr\u00e9dito se ampliaron ligeramente en ambos lados del Atl\u00e1ntico, reflejo de una <strong>mayor aversi\u00f3n al riesgo y del ajuste generalizado en valoraciones<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center; margin-bottom: 10px;\"><a \nhref=\"https:\/\/www.tressis.com\/tressis-vision\/?utm_source=web_publica&amp;utm_medium=direct&amp;utm_campaign=descarga_paper&amp;utm_term=tressisvision&amp;utm_content=blog_MMV\" \ntarget=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" class=\"aligncenter wp-image-67199 size-full\" \nsrc=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg\" \nalt=\"Informe mensual - Tressis visi\u00f3n\" width=\"800\" height=\"354\" style=\"aspect-ratio: 400 \/ 177;\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg 800w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-300x133.jpg 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-768x340.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<h2><strong>A la espera de datos oficiales<\/strong><\/h2>\n<p>El mercado digiere la reapertura de la Administraci\u00f3n estadounidense tras el largo <em>shutdown<\/em>, aunque persisten dudas sobre los plazos de reactivaci\u00f3n del aparato estad\u00edstico y el impacto sobre la publicaci\u00f3n de datos clave. Con la incertidumbre sobre la disponibilidad de cifras oficiales, los inversores se apoyan en indicadores privados mientras calibran si la Fed contar\u00e1 con suficiente informaci\u00f3n para justificar un recorte en diciembre. Los operadores mantienen las probabilidades pr\u00e1cticamente equilibradas, aunque <strong>la volatilidad ha aumentado<\/strong> ante la ausencia de catalizadores claros y la <strong>presi\u00f3n sobre las valoraciones tecnol\u00f3gicas<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center; margin-bottom:20px;\">Probabilidad de recorte de tipos de la Fed.<\/p>\n<div style=\"text-align: center; margin-bottom: 10px;\"><img decoding=\"async\" src=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/fed-20251114.webp\" width=\"1068\" height=\"858\" alt=\"Fed 14\/11\/2025\" class=\"wp-image-113387\" style=\"aspect-ratio: 178 \/ 143;\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/fed-20251114.webp 1068w, https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/fed-20251114-300x241.webp 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/fed-20251114-1024x823.webp 1024w, https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/fed-20251114-768x617.webp 768w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/div>\n<p style=\"text-align: center; margin:20px auto;\" class=\"smallPie\">Fuente: Fed Watch &#8211; CME Group.<\/p>\n<p>&nbsp;<\/p>\n<p>Este movimiento se vio amplificado no solo por el enfriamiento en las expectativas de recorte de tipos, sino tambi\u00e9n por la <strong>salida de flujos en los ETF<\/strong>. Como dato relevante, Owen Gunden, un inversor activo desde la era Satoshi, transfiri\u00f3 2.401 BTC a Kraken, lo que intensific\u00f3 los rumores sobre una posible presi\u00f3n vendedora.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>En la agenda macro<\/strong>, los datos tampoco ayudaron a la confianza. El PIB del Reino Unido sorprendi\u00f3 a la baja (-0,1% frente a 0% esperado), mientras que la producci\u00f3n industrial de la zona euro se situ\u00f3 en el 0,2%, lejos del 0,7% previsto. Hoy el foco estar\u00e1 en el <strong>dato de inflaci\u00f3n de Francia y Espa\u00f1a<\/strong>, el <strong>PIB preliminar de la zona euro<\/strong>, as\u00ed como en las renovaciones de solicitudes por <strong>desempleo y la actividad no agr\u00edcola en Estados Unidos<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Feliz viernes. <\/p>\n<p>&nbsp;<\/p>\n<p><center><strong>\u00c1lvaro Lleras Montoya<\/strong><br \/>\nAnalista<\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sesi\u00f3n de ayer dej\u00f3 un tono claramente negativo en los mercados. En Europa, las principales bolsas cerraron en rojo: el DAX lider\u00f3 las ca\u00eddas con un -1,39%, seguido del FTSE 100 (-1,09%), el IBEX 35 (-0,23%) y el CAC 40 (-0,11%). El \u00fanico sector que logr\u00f3 escapar a las ventas fue el inmobiliario (+0,11%), [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":113389,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[],"class_list":["post-113386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morning-meeting"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas\" \/>\n<meta property=\"og:description\" content=\"La sesi\u00f3n de ayer dej\u00f3 un tono claramente negativo en los mercados. En Europa, las principales bolsas cerraron en rojo: el DAX lider\u00f3 las ca\u00eddas con un -1,39%, seguido del FTSE 100 (-1,09%), el IBEX 35 (-0,23%) y el CAC 40 (-0,11%). El \u00fanico sector que logr\u00f3 escapar a las ventas fue el inmobiliario (+0,11%), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-14T11:39:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T15:05:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/aversion-riesgo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Armando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Armando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/\"},\"author\":{\"name\":\"Armando\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\"},\"headline\":\"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas\",\"datePublished\":\"2025-11-14T11:39:15+00:00\",\"dateModified\":\"2025-11-14T15:05:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/\"},\"wordCount\":493,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/aversion-riesgo.webp\",\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/\",\"name\":\"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/aversion-riesgo.webp\",\"datePublished\":\"2025-11-14T11:39:15+00:00\",\"dateModified\":\"2025-11-14T15:05:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/aversion-riesgo.webp\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/aversion-riesgo.webp\",\"width\":1200,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/aversion-riesgo-ante-dudas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morning meeting\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/morning-meeting-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\",\"name\":\"Armando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"caption\":\"Armando\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"ca_ES","og_type":"article","og_title":"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas","og_description":"La sesi\u00f3n de ayer dej\u00f3 un tono claramente negativo en los mercados. En Europa, las principales bolsas cerraron en rojo: el DAX lider\u00f3 las ca\u00eddas con un -1,39%, seguido del FTSE 100 (-1,09%), el IBEX 35 (-0,23%) y el CAC 40 (-0,11%). El \u00fanico sector que logr\u00f3 escapar a las ventas fue el inmobiliario (+0,11%), [&hellip;]","og_url":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2025-11-14T11:39:15+00:00","article_modified_time":"2025-11-14T15:05:02+00:00","og_image":[{"width":1200,"height":531,"url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/aversion-riesgo.webp","type":"image\/webp"}],"author":"Armando","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Armando","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/"},"author":{"name":"Armando","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae"},"headline":"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas","datePublished":"2025-11-14T11:39:15+00:00","dateModified":"2025-11-14T15:05:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/"},"wordCount":493,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/aversion-riesgo.webp","articleSection":["Morning meeting"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/","url":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/","name":"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/aversion-riesgo.webp","datePublished":"2025-11-14T11:39:15+00:00","dateModified":"2025-11-14T15:05:02+00:00","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/aversion-riesgo.webp","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/aversion-riesgo.webp","width":1200,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/aversion-riesgo-ante-dudas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Morning meeting","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/morning-meeting-ca\/"},{"@type":"ListItem","position":3,"name":"Aversi\u00f3n al riesgo ante m\u00e1s dudas macro y tecnol\u00f3gicas"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae","name":"Armando","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","caption":"Armando"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/113386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=113386"}],"version-history":[{"count":1,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/113386\/revisions"}],"predecessor-version":[{"id":113391,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/113386\/revisions\/113391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/113389"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=113386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=113386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=113386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}