{"id":113353,"date":"2025-11-12T10:15:32","date_gmt":"2025-11-12T09:15:32","guid":{"rendered":"https:\/\/www.tressis.com\/?p=113353"},"modified":"2025-11-12T10:19:12","modified_gmt":"2025-11-12T09:19:12","slug":"de-paralisis-al-optimismo","status":"publish","type":"post","link":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/","title":{"rendered":"De la par\u00e1lisis al optimismo"},"content":{"rendered":"<p>La posibilidad de que el mayor cierre gubernamental en la historia de Estados Unidos est\u00e9 cerca de su fin ha devuelto algo de optimismo a los mercados. Wall Street, <strong>siempre dispuesta a celebrar cualquier atisbo de normalidad<\/strong>, cerr\u00f3 la sesi\u00f3n con avances moderados. El S&#038;P 500 subi\u00f3 un 0,2%, mientras que el Dow Jones Industrial Average se anot\u00f3 un 1,2%, impulsado por valores industriales como FedEx, que repunt\u00f3 m\u00e1s de un 5% tras anticipar una mejora de beneficios. En cambio, el Nasdaq 100 cedi\u00f3 un 0,25%, penalizado por la correcci\u00f3n en tecnol\u00f3gicas como Nvidia, que cay\u00f3 un 3% tras la venta de la participaci\u00f3n de SoftBank en la compa\u00f1\u00eda. El tono fue algo m\u00e1s constructivo en los mercados globales \u2014el MSCI World avanz\u00f3 un 0,4%\u2014, as\u00ed como en Europa, donde el SMI suizo subi\u00f3 m\u00e1s de un 2%, mientras el Eurostoxx 50 lo hac\u00eda en un 1,1%.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>En el frente de las divisas<\/strong><\/h2>\n<p>El d\u00f3lar se mantuvo pr\u00e1cticamente plano, con el euro apreci\u00e1ndose un ligero 0,2% hasta los 1,1584 d\u00f3lares, despu\u00e9s de llegar a cotizar por encima del 1,16. Las criptomonedas, por su parte, siguen demostrando que la euforia tambi\u00e9n tiene resacas: el bitcoin cay\u00f3 un 2,7%, hasta los 102.734 d\u00f3lares, y Ethereum  retrocedi\u00f3 un 3,5%.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Mercado de bonos<\/strong><\/h2>\n<p>En los mercados de renta fija, los bonos europeos vivieron una sesi\u00f3n de consolidaci\u00f3n. La rentabilidad del diez a\u00f1os alem\u00e1n descendi\u00f3 un punto b\u00e1sico, hasta el 2,66%, y la del <em>gilt<\/em> brit\u00e1nico cay\u00f3 siete, hasta el 4,39%. Con el mercado estadounidense cerrado por el D\u00eda de los Veteranos, los futuros sobre Treasuries subieron apoyados en unos datos privados de empleo que apuntan a <strong>cierta moderaci\u00f3n del mercado laboral<\/strong> en la segunda mitad de octubre.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Materias primas<\/strong><\/h2>\n<p>El petr\u00f3leo WTI repunt\u00f3 un 1,5%, hasta los 61,05 d\u00f3lares el barril, apoyado por las <strong>expectativas de un mayor consumo con el fin del cierre administrativo<\/strong>. El oro, tradicional refugio, avanz\u00f3 un 0,3%, hasta los 4.128 d\u00f3lares la onza. No parece que el metal precioso est\u00e9 atrayendo demasiadas compras, s\u00edntoma de que, al menos por ahora, el mercado no teme grandes sobresaltos.<\/p>\n<p>&nbsp;<\/p>\n<div style=\"text-align: center; margin-bottom: 10px;\"><a \nhref=\"https:\/\/www.tressis.com\/tressis-vision\/?utm_source=web_publica&amp;utm_medium=direct&amp;utm_campaign=descarga_paper&amp;utm_term=tressisvision&amp;utm_content=blog_MMV\" \ntarget=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" class=\"aligncenter wp-image-67199 size-full\" \nsrc=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg\" \nalt=\"Informe mensual - Tressis visi\u00f3n\" width=\"800\" height=\"354\" style=\"aspect-ratio: 400 \/ 177;\" srcset=\"https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog.jpg 800w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-300x133.jpg 300w, https:\/\/www.tressis.com\/wp-content\/uploads\/2023\/03\/CTA-Tressis-vision-para-articulos-blog-768x340.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<h2><strong>Final del <em>shutdown<\/em><\/strong><\/h2>\n<p>Estos d\u00edas toca estar atentos a la reapertura de la Administraci\u00f3n de EE.UU., que lleva m\u00e1s de cuarenta d\u00edas cerrada y ya <strong>empieza a notarse en la econom\u00eda y en el \u00e1nimo de los mercados<\/strong>. Con suerte, el regreso a la normalidad ser\u00e1 r\u00e1pido y volver\u00e1n los datos econ\u00f3micos habituales. El Senado ha aprobado un acuerdo temporal de financiaci\u00f3n hasta finales de enero, y ahora la atenci\u00f3n se centra en la C\u00e1mara de Representantes. Si el texto prospera, se reactivar\u00e1n las agencias federales y, con ellas, el flujo de indicadores que lleva semanas en silencio. La falta de datos oficiales ha obligado a los analistas a apoyarse en cifras privadas, pero el mercado ya descuenta que la reapertura permitir\u00e1 conocer pronto los <strong>informes de empleo y actividad pendientes<\/strong>. Hoy tambi\u00e9n habr\u00e1 que seguir de cerca las subastas de bonos en EE.UU., que podr\u00edan ofrecer pistas sobre la demanda de deuda p\u00fablica en un contexto de alta emisi\u00f3n, y los nuevos datos de inflaci\u00f3n de varios pa\u00edses de la eurozona, con Alemania a la cabeza.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, varios miembros de la Reserva Federal hablar\u00e1n en los pr\u00f3ximos d\u00edas, y sus mensajes pueden dar pistas sobre la evoluci\u00f3n de la pol\u00edtica monetaria. Aunque el tono general del mercado sigue siendo optimista, <strong>la inflaci\u00f3n contin\u00faa preocupando<\/strong> y podr\u00eda frenar nuevos recortes de tipos.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Pol\u00edticas monetarias<\/strong><\/h2>\n<p>El consenso de mercado en Estados Unidos sigue apostando por que la Fed adopte un tono m\u00e1s acomodaticio en diciembre, una perspectiva que ha contribuido a mantener viva la narrativa del \u201c<em>rally<\/em> de fin de a\u00f1o\u201d. Algo parecido ocurre en el Reino Unido, donde el Banco de Inglaterra decidi\u00f3 hacer una pausa la semana pasada. Con el desempleo brit\u00e1nico ya en el 5%, todos esperan comprobar si finalmente el banco central se decide a iniciar un ciclo de bajadas en los pr\u00f3ximos meses. <strong>Los inversores europeos miran de reojo al BCE<\/strong>, que tambi\u00e9n ha suavizado su discurso, aunque sin comprometerse a\u00fan a una senda de recortes.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Las tecnol\u00f3gicas no levantan el pie del acelerador<\/strong><\/h2>\n<p>El entusiasmo se nota especialmente en torno a la <strong>inversi\u00f3n en inteligencia artificial<\/strong>. SoftBank ha liquidado su posici\u00f3n en Nvidia por 5.830 millones de d\u00f3lares para financiar nuevos proyectos en el sector, mientras Microsoft planea destinar <strong>10.000 millones a un centro de datos en Portugal<\/strong> y Google invertir\u00e1 <strong>6.400 millones en Alemania<\/strong>. Todo ello ha reforzado la idea de que el ciclo de inversi\u00f3n tecnol\u00f3gica apenas ha comenzado. Sin embargo, algunas voces advierten que el mercado podr\u00eda estar pasando por alto los riesgos de sobreinversi\u00f3n y los m\u00e1rgenes cada vez m\u00e1s ajustados en las grandes tecnol\u00f3gicas. Pero es cierto que este a\u00f1o se ha hablado menos de las ventas online por el D\u00eda del Soltero en China. <\/p>\n<p>&nbsp;<\/p>\n<p>Hist\u00f3ricamente, el S&#038;P 500 ha subido un 2,3% en el mes posterior al fin de un cierre administrativo. Si el patr\u00f3n se repite, el \u00edndice podr\u00eda acercarse a los 7.000 puntos a mediados de diciembre, una cifra que suena <strong>tan redonda como optimista<\/strong>. Claro que, como suele suceder, la realidad podr\u00eda tener otros planes.<\/p>\n<p>&nbsp;<\/p>\n<p>De momento, el mercado prefiere ver el vaso medio lleno. <strong>Las grandes compa\u00f1\u00edas siguen presentando beneficios razonables, los bancos centrales insin\u00faan cierta flexibilidad y el miedo a una recesi\u00f3n se ha tomado un descanso.<\/strong> Queda por ver si la vuelta a la \u201cnormalidad\u201d en Washington mantiene el buen tono o si, como tantas veces, el <em>rally<\/em> de fin de a\u00f1o se queda en una historia bien contada.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00a1A por el mi\u00e9rcoles! <\/p>\n<p>&nbsp;<\/p>\n<p><center><strong>Jorge Gonz\u00e1lez G\u00f3mez<\/strong><br \/>\nDirector de An\u00e1lisis<\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La posibilidad de que el mayor cierre gubernamental en la historia de Estados Unidos est\u00e9 cerca de su fin ha devuelto algo de optimismo a los mercados. Wall Street, siempre dispuesta a celebrar cualquier atisbo de normalidad, cerr\u00f3 la sesi\u00f3n con avances moderados. El S&#038;P 500 subi\u00f3 un 0,2%, mientras que el Dow Jones Industrial [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":113354,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9721],"tags":[],"class_list":["post-113353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-morning-meeting"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De la par\u00e1lisis al optimismo<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De la par\u00e1lisis al optimismo\" \/>\n<meta property=\"og:description\" content=\"La posibilidad de que el mayor cierre gubernamental en la historia de Estados Unidos est\u00e9 cerca de su fin ha devuelto algo de optimismo a los mercados. Wall Street, siempre dispuesta a celebrar cualquier atisbo de normalidad, cerr\u00f3 la sesi\u00f3n con avances moderados. El S&#038;P 500 subi\u00f3 un 0,2%, mientras que el Dow Jones Industrial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tressis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tressis\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-12T09:15:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-12T09:19:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/mw.tressis.com\/wp-content\/uploads\/2025\/11\/de-paralisis-al-optimismo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Armando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:site\" content=\"@TressisSV\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Armando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/\"},\"author\":{\"name\":\"Armando\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\"},\"headline\":\"De la par\u00e1lisis al optimismo\",\"datePublished\":\"2025-11-12T09:15:32+00:00\",\"dateModified\":\"2025-11-12T09:19:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/\"},\"wordCount\":1012,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/de-paralisis-al-optimismo.webp\",\"articleSection\":[\"Morning meeting\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/\",\"name\":\"De la par\u00e1lisis al optimismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/de-paralisis-al-optimismo.webp\",\"datePublished\":\"2025-11-12T09:15:32+00:00\",\"dateModified\":\"2025-11-12T09:19:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/de-paralisis-al-optimismo.webp\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/de-paralisis-al-optimismo.webp\",\"width\":1200,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/de-paralisis-al-optimismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morning meeting\",\"item\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/blog\\\/categorias\\\/morning-meeting-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"De la par\u00e1lisis al optimismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"name\":\"Tressis banca privada\",\"description\":\"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#organization\",\"name\":\"Tressis\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"contentUrl\":\"https:\\\/\\\/www.tressis.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-tressis-112.png\",\"width\":112,\"height\":112,\"caption\":\"Tressis\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tressis\\\/\",\"https:\\\/\\\/x.com\\\/TressisSV\",\"https:\\\/\\\/www.instagram.com\\\/tressissv\\\/?hl=es\",\"https:\\\/\\\/linkedin.com\\\/company\\\/tressis\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/tressissv\",\"https:\\\/\\\/open.spotify.com\\\/show\\\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tressis.com\\\/ca\\\/#\\\/schema\\\/person\\\/56d3b4de0493f088a4ca62a2e0c790ae\",\"name\":\"Armando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g\",\"caption\":\"Armando\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De la par\u00e1lisis al optimismo","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"ca_ES","og_type":"article","og_title":"De la par\u00e1lisis al optimismo","og_description":"La posibilidad de que el mayor cierre gubernamental en la historia de Estados Unidos est\u00e9 cerca de su fin ha devuelto algo de optimismo a los mercados. Wall Street, siempre dispuesta a celebrar cualquier atisbo de normalidad, cerr\u00f3 la sesi\u00f3n con avances moderados. El S&#038;P 500 subi\u00f3 un 0,2%, mientras que el Dow Jones Industrial [&hellip;]","og_url":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/","og_site_name":"Tressis","article_publisher":"https:\/\/www.facebook.com\/Tressis\/","article_published_time":"2025-11-12T09:15:32+00:00","article_modified_time":"2025-11-12T09:19:12+00:00","og_image":[{"width":1200,"height":531,"url":"http:\/\/mw.tressis.com\/wp-content\/uploads\/2025\/11\/de-paralisis-al-optimismo.webp","type":"image\/webp"}],"author":"Armando","twitter_card":"summary_large_image","twitter_creator":"@TressisSV","twitter_site":"@TressisSV","twitter_misc":{"Escrit per":"Armando","Temps estimat de lectura":"5 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/#article","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/"},"author":{"name":"Armando","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae"},"headline":"De la par\u00e1lisis al optimismo","datePublished":"2025-11-12T09:15:32+00:00","dateModified":"2025-11-12T09:19:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/"},"wordCount":1012,"publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/de-paralisis-al-optimismo.webp","articleSection":["Morning meeting"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/","url":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/","name":"De la par\u00e1lisis al optimismo","isPartOf":{"@id":"https:\/\/www.tressis.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/#primaryimage"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/de-paralisis-al-optimismo.webp","datePublished":"2025-11-12T09:15:32+00:00","dateModified":"2025-11-12T09:19:12+00:00","breadcrumb":{"@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/#primaryimage","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/de-paralisis-al-optimismo.webp","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/11\/de-paralisis-al-optimismo.webp","width":1200,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/www.tressis.com\/ca\/blog\/de-paralisis-al-optimismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.tressis.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Morning meeting","item":"https:\/\/www.tressis.com\/ca\/blog\/categorias\/morning-meeting-ca\/"},{"@type":"ListItem","position":3,"name":"De la par\u00e1lisis al optimismo"}]},{"@type":"WebSite","@id":"https:\/\/www.tressis.com\/ca\/#website","url":"https:\/\/www.tressis.com\/ca\/","name":"Tressis banca privada","description":"Tressis | Planificaci\u00f3n financiera y gesti\u00f3n de patrimonios","publisher":{"@id":"https:\/\/www.tressis.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tressis.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.tressis.com\/ca\/#organization","name":"Tressis","url":"https:\/\/www.tressis.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","contentUrl":"https:\/\/www.tressis.com\/wp-content\/uploads\/2025\/06\/logo-tressis-112.png","width":112,"height":112,"caption":"Tressis"},"image":{"@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tressis\/","https:\/\/x.com\/TressisSV","https:\/\/www.instagram.com\/tressissv\/?hl=es","https:\/\/linkedin.com\/company\/tressis\/","https:\/\/www.youtube.com\/user\/tressissv","https:\/\/open.spotify.com\/show\/3jmTe1Nf0wqMILl7diWV6h?si=d7112519f13c4593&nd=1"]},{"@type":"Person","@id":"https:\/\/www.tressis.com\/ca\/#\/schema\/person\/56d3b4de0493f088a4ca62a2e0c790ae","name":"Armando","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7efca74644be7dae792b122beab663996c233ae58f101b52769ece1cbf1435?s=96&d=mm&r=g","caption":"Armando"}}]}},"_links":{"self":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/113353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/comments?post=113353"}],"version-history":[{"count":2,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/113353\/revisions"}],"predecessor-version":[{"id":113357,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/posts\/113353\/revisions\/113357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media\/113354"}],"wp:attachment":[{"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/media?parent=113353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/categories?post=113353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tressis.com\/ca\/wp-json\/wp\/v2\/tags?post=113353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}